{"id":5967,"date":"2025-07-26T12:22:15","date_gmt":"2025-07-26T15:22:15","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=5967"},"modified":"2025-07-26T12:22:16","modified_gmt":"2025-07-26T15:22:16","slug":"policia-desarticula-esquema-de-furtos-de-baterias-em-itabaiana-ribeiropolis-e-mais-cinco-cidades","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/07\/26\/policia-desarticula-esquema-de-furtos-de-baterias-em-itabaiana-ribeiropolis-e-mais-cinco-cidades\/","title":{"rendered":"Pol\u00edcia desarticula esquema de furtos de baterias em Itabaiana, Ribeir\u00f3polis e mais cinco cidades"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Uma for\u00e7a-tarefa coordenada pela Pol\u00edcia Civil de Sergipe resultou, na noite desta quinta-feira (24), na localiza\u00e7\u00e3o do principal suspeito de integrar uma rede criminosa respons\u00e1vel por uma s\u00e9rie de furtos de baterias automotivas no estado. A opera\u00e7\u00e3o, batizada de&nbsp;<em><strong>Circuito Fechado<\/strong><\/em>, contou com a atua\u00e7\u00e3o da 2\u00aa Delegacia Metropolitana (DM) e o apoio do Departamento de Intelig\u00eancia e Planejamento Policial (Dipol), com foco especial na cidade de Itabaiana, um dos principais alvos do suspeito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s oito meses de investiga\u00e7\u00f5es minuciosas, a pol\u00edcia identificou&nbsp;<strong>Domingos dos Santos Neto<\/strong>como o articulador de uma sequ\u00eancia de crimes que abrangeu pelo menos sete munic\u00edpios sergipanos. Al\u00e9m de Itabaiana, foram registradas ocorr\u00eancias em Aracaju, Nossa Senhora do Socorro, Ribeir\u00f3polis, Ros\u00e1rio do Catete, Capela e S\u00e3o Crist\u00f3v\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o delegado respons\u00e1vel pelo caso, o criminoso agia com precis\u00e3o cir\u00fargica. Durante as madrugadas, escolhia locais com pouca movimenta\u00e7\u00e3o e arrombava compartimentos de seguran\u00e7a de ve\u00edculos pesados \u2014 como caminh\u00f5es e \u00f4nibus \u2014 para subtrair as baterias. Em seguida, empreendia fuga de forma arriscada, utilizando manobras como r\u00e9 e contram\u00e3o para despistar eventuais testemunhas ou c\u00e2meras de monitoramento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A an\u00e1lise de imagens de seguran\u00e7a coletadas em com\u00e9rcios e resid\u00eancias foi essencial para comprovar a atua\u00e7\u00e3o em s\u00e9rie e estabelecer o padr\u00e3o dos furtos. Al\u00e9m disso, Domingos j\u00e1 possu\u00eda antecedentes criminais registrados entre 2007 e 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante da gravidade dos crimes e da possibilidade de reincid\u00eancia, a Pol\u00edcia Civil solicitou a pris\u00e3o preventiva do investigado, deferida pela Justi\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A opera\u00e7\u00e3o teve um desfecho violento. Durante o cumprimento do mandado judicial, na regi\u00e3o da ponte Construtor Jo\u00e3o Alves \u2014 que liga Aracaju a Barra dos Coqueiros \u2014 o suspeito reagiu \u00e0 abordagem e efetuou disparos contra os policiais. Houve confronto. Domingos foi socorrido, mas n\u00e3o resistiu aos ferimentos e morreu ap\u00f3s dar entrada no Hospital de Urg\u00eancia de Sergipe (Huse).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com ele, foram apreendidos uma arma de fogo, ferramentas usadas nos arrombamentos, baterias furtadas e o ve\u00edculo utilizado nas a\u00e7\u00f5es criminosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Itnet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Uma for\u00e7a-tarefa coordenada pela Pol\u00edcia Civil de Sergipe resultou, na noite desta quinta-feira (24), na localiza\u00e7\u00e3o do principal suspeito de integrar uma rede criminosa respons\u00e1vel por uma s\u00e9rie de furtos de baterias automotivas no estado. A opera\u00e7\u00e3o, batizada de&nbsp;Circuito Fechado, contou com a atua\u00e7\u00e3o da 2\u00aa Delegacia Metropolitana (DM) e o apoio do Departamento de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/07\/IMG_4071.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5967"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5967\/revisions"}],"predecessor-version":[{"id":5969,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5967\/revisions\/5969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/5968"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}