{"id":5976,"date":"2025-07-28T08:11:01","date_gmt":"2025-07-28T11:11:01","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=5976"},"modified":"2025-07-28T08:11:03","modified_gmt":"2025-07-28T11:11:03","slug":"tres-pessoas-ficam-feridas-apos-acidente-entre-dois-carros-em-simao-dias","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/07\/28\/tres-pessoas-ficam-feridas-apos-acidente-entre-dois-carros-em-simao-dias\/","title":{"rendered":"Tr\u00eas pessoas ficam feridas ap\u00f3s acidente entre dois carros em Sim\u00e3o Dias"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um acidente do tipo colis\u00e3o lateral deixou tr\u00eas pessoas feridas na noite deste domingo (27), na Rodovia SE-270, nas proximidades do povoado Quilombo, no munic\u00edpio de Sim\u00e3o Dias, interior de Sergipe. O fato ocorreu por volta das 22h05 e mobilizou equipes do Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual (BPRv), do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) e do Corpo de Bombeiros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/imagens.f5news.com.br\/arquivos\/2025\/07\/tres-pessoas-ficam-f_173221753700810.jpg\"><\/a>BPRv<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com informa\u00e7\u00f5es da pol\u00edcia, o acidente envolveu dois autom\u00f3veis que trafegavam em sentidos opostos. Um dos ve\u00edculos seguia no sentido Lagarto\u2013Sim\u00e3o Dias, quando colidiu lateralmente com o outro autom\u00f3vel, que vinha na dire\u00e7\u00e3o contr\u00e1ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O condutor do primeiro carro foi socorrido pelo SAMU e encaminhado ao hospital. O motorista e a passageira do segundo ve\u00edculo ficaram presos \u00e0s ferragens e precisaram ser resgatados pelo Corpo de Bombeiros. Ambos tamb\u00e9m foram levados ao Hospital Universit\u00e1rio de Lagarto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Devido \u00e0 gravidade do acidente, n\u00e3o foi poss\u00edvel realizar o teste do etil\u00f4metro no local. A guarni\u00e7\u00e3o se deslocou at\u00e9 o hospital para a verifica\u00e7\u00e3o. O condutor do primeiro ve\u00edculo recusou-se a fazer o teste, sendo lavrado termo de recusa. J\u00e1 o motorista do segundo carro se submeteu ao exame, que deu negativo para ingest\u00e3o de \u00e1lcool.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: F5news<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um acidente do tipo colis\u00e3o lateral deixou tr\u00eas pessoas feridas na noite deste domingo (27), na Rodovia SE-270, nas proximidades do povoado Quilombo, no munic\u00edpio de Sim\u00e3o Dias, interior de Sergipe. O fato ocorreu por volta das 22h05 e mobilizou equipes do Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual (BPRv), do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/07\/IMG_4087.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5976"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5976\/revisions"}],"predecessor-version":[{"id":5978,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5976\/revisions\/5978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/5977"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}