{"id":6030,"date":"2025-08-06T09:55:52","date_gmt":"2025-08-06T12:55:52","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6030"},"modified":"2025-08-06T09:55:54","modified_gmt":"2025-08-06T12:55:54","slug":"itabaiana-denarc-prende-suspeito-com-150g-de-crack-e-material-para-trafico","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/08\/06\/itabaiana-denarc-prende-suspeito-com-150g-de-crack-e-material-para-trafico\/","title":{"rendered":"Itabaiana: Denarc prende suspeito com 150g de crack e material para tr\u00e1fico"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Policiais civis da Divis\u00e3o de Narc\u00f3ticos e Entorpecentes da Delegacia Regional de Itabaiana realizaram, na tarde da \u00faltima ter\u00e7a-feira (5), a pris\u00e3o em flagrante de um jovem de 18 anos, identificado pelas iniciais V.S.S., suspeito de envolvimento com o tr\u00e1fico de drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o aconteceu na rua Jos\u00e9 Braz Santos Oliveira, no bairro S\u00e3o Crist\u00f3v\u00e3o, resultado de investiga\u00e7\u00f5es que indicavam a participa\u00e7\u00e3o do suspeito na comercializa\u00e7\u00e3o de entorpecentes e porte ilegal de arma de fogo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a abordagem, foram apreendidas diversas trouxas de maconha, material para embalar, uma balan\u00e7a de precis\u00e3o, um caderno com anota\u00e7\u00f5es sobre d\u00edvidas de venda e cerca de 150 gramas de crack em pedra bruta \u2014 que poderiam ser fracionadas em at\u00e9 1.800 pedras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O jovem foi encaminhado \u00e0 Delegacia Regional de Itabaiana, onde foi lavrado o auto de pris\u00e3o em flagrante por tr\u00e1fico de drogas. Ele segue \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Portal Itnet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Policiais civis da Divis\u00e3o de Narc\u00f3ticos e Entorpecentes da Delegacia Regional de Itabaiana realizaram, na tarde da \u00faltima ter\u00e7a-feira (5), a pris\u00e3o em flagrante de um jovem de 18 anos, identificado pelas iniciais V.S.S., suspeito de envolvimento com o tr\u00e1fico de drogas. A a\u00e7\u00e3o aconteceu na rua Jos\u00e9 Braz Santos Oliveira, no bairro S\u00e3o Crist\u00f3v\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6031,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/08\/IMG_4304.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6030"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6030\/revisions"}],"predecessor-version":[{"id":6032,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6030\/revisions\/6032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6031"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}