{"id":6036,"date":"2025-08-07T15:50:25","date_gmt":"2025-08-07T18:50:25","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6036"},"modified":"2025-08-07T15:50:26","modified_gmt":"2025-08-07T18:50:26","slug":"acidente-entre-duas-motos-e-um-carro-deixa-dois-feridos-na-ponte-da-barra-dos-coqueiros","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/08\/07\/acidente-entre-duas-motos-e-um-carro-deixa-dois-feridos-na-ponte-da-barra-dos-coqueiros\/","title":{"rendered":"Acidente entre duas motos e um carro deixa dois feridos na ponte da Barra dos Coqueiros"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Dois motociclistas ficaram feridos ap\u00f3s um acidente envolvendo tr\u00eas ve\u00edculos na \u00faltima quarta-feira (6), na Rodovia SE-100, na ponte da Barra dos Coqueiros, sentido Barra\/Aracaju.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Pol\u00edcia Militar (PM), o carro estava parado na via devido a problemas mec\u00e2nicos quando foi atingido na traseira por uma motocicleta. Na sequ\u00eancia, uma segunda motocicleta colidiu na traseira da primeira moto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A passageira da primeira moto e o condutor da segunda foram socorridos e encaminhados ao Hospital Nestor Piva. Os demais envolvidos n\u00e3o sofreram ferimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O teste do baf\u00f4metro foi realizado nos condutores do carro e da moto, ambos com resultado negativo para ingest\u00e3o de \u00e1lcool. O condutor da outra motocicleta n\u00e3o foi testado por estar hospitalizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os ve\u00edculos foram liberados aos respons\u00e1veis e n\u00e3o houve necessidade de remo\u00e7\u00e3o ou aplica\u00e7\u00e3o de autos de infra\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Dois motociclistas ficaram feridos ap\u00f3s um acidente envolvendo tr\u00eas ve\u00edculos na \u00faltima quarta-feira (6), na Rodovia SE-100, na ponte da Barra dos Coqueiros, sentido Barra\/Aracaju. De acordo com a Pol\u00edcia Militar (PM), o carro estava parado na via devido a problemas mec\u00e2nicos quando foi atingido na traseira por uma motocicleta. Na sequ\u00eancia, uma segunda motocicleta [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/08\/IMG_4341.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6036"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6036\/revisions"}],"predecessor-version":[{"id":6038,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6036\/revisions\/6038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6037"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}