{"id":6128,"date":"2025-08-27T10:49:54","date_gmt":"2025-08-27T13:49:54","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6128"},"modified":"2025-08-27T10:49:55","modified_gmt":"2025-08-27T13:49:55","slug":"ponte-aracaju-barra-sera-parcialmente-interditada-a-partir-desta-quarta-feira","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/08\/27\/ponte-aracaju-barra-sera-parcialmente-interditada-a-partir-desta-quarta-feira\/","title":{"rendered":"Ponte Aracaju-Barra ser\u00e1 parcialmente interditada a partir desta quarta-feira"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A ponte Construtor Jo\u00e3o Alves, que liga os munic\u00edpios&nbsp;Aracaju&nbsp;e&nbsp;Barra dos Coqueiros, ser\u00e1 parcialmente interditada a partir desta quarta-feira (27) para a realiza\u00e7\u00e3o de obras de moderniza\u00e7\u00e3o na rede el\u00e9trica. O servi\u00e7oestava previsto para iniciar nesta segunda-feira, mas teve a data alterada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A interdi\u00e7\u00e3o ser\u00e1 realizada das 9h \u00e0s 15h em uma das vias da ponte at\u00e9 o m\u00eas de setembro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Energisa, o hor\u00e1rio foi definido de forma a n\u00e3o comprometer o fornecimento de energia para os clientes de Barra dos Coqueiros \u00e0 noite, per\u00edodo de pico de utiliza\u00e7\u00e3o do servi\u00e7o, e no intervalo de menor intensidade no tr\u00e2nsito, como forma de minimizar os impactos aos motoristas que trafegam na regi\u00e3o. A primeira mudan\u00e7a aconteceu nesta segunda-feira (25) com a transfer\u00eancia do fluxo da passarela de pedestre para a faixa no sentido Aracaju\/Barra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda est\u00e3o previstas a\u00e7\u00f5es de reforma da rede el\u00e9trica, com a constru\u00e7\u00e3o de novos circuitos, e moderniza\u00e7\u00e3o de redes em trechos da cidade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o conjunto de a\u00e7\u00f5es, os clientes podem receber avisos de desligamentos programados que s\u00e3o interrup\u00e7\u00f5es no fornecimento de energia de forma programada para que a melhoria na rede seja realizada com seguran\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A ponte Construtor Jo\u00e3o Alves, que liga os munic\u00edpios&nbsp;Aracaju&nbsp;e&nbsp;Barra dos Coqueiros, ser\u00e1 parcialmente interditada a partir desta quarta-feira (27) para a realiza\u00e7\u00e3o de obras de moderniza\u00e7\u00e3o na rede el\u00e9trica. O servi\u00e7oestava previsto para iniciar nesta segunda-feira, mas teve a data alterada. A interdi\u00e7\u00e3o ser\u00e1 realizada das 9h \u00e0s 15h em uma das vias da ponte [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/08\/IMG_4759.webp","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6128"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6128\/revisions"}],"predecessor-version":[{"id":6130,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6128\/revisions\/6130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6129"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}