{"id":6165,"date":"2025-08-14T12:41:03","date_gmt":"2025-08-14T15:41:03","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6165"},"modified":"2025-09-10T10:53:14","modified_gmt":"2025-09-10T13:53:14","slug":"feirantes-de-sergipe-comemoram-novo-auxilio-do-governo-do-estado","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/08\/14\/feirantes-de-sergipe-comemoram-novo-auxilio-do-governo-do-estado\/","title":{"rendered":"Feirantes de Sergipe comemoram novo aux\u00edlio do Governo do Estado"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\"><em>Benef\u00edcio da nova modalidade do Cart\u00e3o CMais ser\u00e1 de R$ 200 por m\u00eas e vai contemplar at\u00e9 2 mil trabalhadores aut\u00f4nomos<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amplia\u00e7\u00e3o de renda e garantia de mais dignidade e direitos. S\u00e3o esses os objetivos do CMais Feirante, programa do Governo de Sergipe, executado pela Secretaria de Estado da Assist\u00eancia Social, Inclus\u00e3o e Cidadania (Seasic), que vai oferecer R$ 200 mensais a 2 mil feirantes e ambulantes em vulnerabilidade social durante 12 meses. O aux\u00edlio representa um respiro financeiro, movimenta a economia local e assegura mais inclus\u00e3o para o setor, que celebra a iniciativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quem comemorou foi o feirante Jos\u00e9 Luciano Santos Siqueira, que atua h\u00e1 20 anos na feira livre de Itabaiana, munic\u00edpio do agreste onde o programa foi lan\u00e7ado. Ele contou que o benef\u00edcio vai ajudar a compensar os dias de baixas vendas, j\u00e1 que nem sempre h\u00e1 uma boa sa\u00edda de produtos de sua banca. Para Jos\u00e9 Luciano, os R$ 2.400 por ano v\u00e3o fazer diferen\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVai ser uma grande ajuda para a gente. Tem dias que est\u00e1 mais fraco e tem dias que est\u00e1 mais forte. Tem essa varia\u00e7\u00e3o nas vendas. Ent\u00e3o, \u00e9 algo que vai contribuir para todos n\u00f3s. O governo est\u00e1 de parab\u00e9ns por esse novo aux\u00edlio\u201d, destacou ele. Ao todo, a a\u00e7\u00e3o de transfer\u00eancia de renda vai injetar R$ 4,8 milh\u00f5es na economia sergipana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Custos diminu\u00eddos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destinado a inscritos no Cadastro \u00danico (Cad\u00danico), o CMais Feirante vai contribuir diretamente para que os trabalhadores continuem atuando. Foi isso que afirmou a feirante Solange Oliveira Santos, que atua em Itabaiana. Segundo ela, o aumento de pre\u00e7o de mercadorias tem impactado no rendimento mensal. Agora, com o benef\u00edcio, a realidade muda para melhor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTem alguns desafios. As feiras est\u00e3o devagar e o custo dos produtos tem crescido. A gente faz um investimento alto para poder vender. Por isso, uma ajuda como essa \u00e9 muito importante. Vem em um momento \u00f3timo\u201d, avaliou ela. Para Solange, o aux\u00edlio vai aliviar os gastos e contribuir para que ela possa adquirir mais itens para sua banca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quem pode participar?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podem se inscrever no programa feirantes, ambulantes e comerciantes de g\u00eaneros aliment\u00edcios que exer\u00e7am a atividade em espa\u00e7os p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quais os crit\u00e9rios para ser benefici\u00e1rio do CMais Feirante?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf estar com registro atualizado no Cad\u00danico;<br>\u25cf ser maior de 18 anos de idade ou respons\u00e1vel familiar no Cad\u00danico;<br>\u25cf n\u00e3o receber nenhum outro benef\u00edcio do Governo do Estado;<br>\u25cf e comprovar inscri\u00e7\u00e3o no cadastro municipal da cidade onde atua.<br>Como se inscrever para o programa?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As inscri\u00e7\u00f5es s\u00e3o realizadas online por meio do link <a href=\"https:\/\/cmaisinscricoes.assistenciasocial.se.gov.br\/.\">https:\/\/cmaisinscricoes.assistenciasocial.se.gov.br\/.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"6166\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/b85cd392-7ed7-46eb-8ebb-040031d32aa8-1024x682.jpeg\" alt=\"\" class=\"wp-image-6166\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/b85cd392-7ed7-46eb-8ebb-040031d32aa8-1024x682.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/b85cd392-7ed7-46eb-8ebb-040031d32aa8-300x200.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/b85cd392-7ed7-46eb-8ebb-040031d32aa8-768x512.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/b85cd392-7ed7-46eb-8ebb-040031d32aa8-1536x1023.jpeg 1536w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/b85cd392-7ed7-46eb-8ebb-040031d32aa8-360x240.jpeg 360w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/b85cd392-7ed7-46eb-8ebb-040031d32aa8.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"6167\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/e932beb7-d5f4-4e62-935f-9417aae51348-1024x682.jpeg\" alt=\"\" class=\"wp-image-6167\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/e932beb7-d5f4-4e62-935f-9417aae51348-1024x682.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/e932beb7-d5f4-4e62-935f-9417aae51348-300x200.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/e932beb7-d5f4-4e62-935f-9417aae51348-768x512.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/e932beb7-d5f4-4e62-935f-9417aae51348-1536x1023.jpeg 1536w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/e932beb7-d5f4-4e62-935f-9417aae51348-360x240.jpeg 360w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/e932beb7-d5f4-4e62-935f-9417aae51348.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"6168\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/9bfa21c2-c41b-4e53-94be-815b68a0f947-1024x682.jpeg\" alt=\"\" class=\"wp-image-6168\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/9bfa21c2-c41b-4e53-94be-815b68a0f947-1024x682.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/9bfa21c2-c41b-4e53-94be-815b68a0f947-300x200.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/9bfa21c2-c41b-4e53-94be-815b68a0f947-768x512.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/9bfa21c2-c41b-4e53-94be-815b68a0f947-1536x1023.jpeg 1536w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/9bfa21c2-c41b-4e53-94be-815b68a0f947-360x240.jpeg 360w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/9bfa21c2-c41b-4e53-94be-815b68a0f947.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Benef\u00edcio da nova modalidade do Cart\u00e3o CMais ser\u00e1 de R$ 200 por m\u00eas e vai contemplar at\u00e9 2 mil trabalhadores aut\u00f4nomos Amplia\u00e7\u00e3o de renda e garantia de mais dignidade e direitos. S\u00e3o esses os objetivos do CMais Feirante, programa do Governo de Sergipe, executado pela Secretaria de Estado da Assist\u00eancia Social, Inclus\u00e3o e Cidadania (Seasic), [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/3876618a-386f-4547-bae0-2a356c7d5ad4.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6165"}],"version-history":[{"count":2,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6165\/revisions"}],"predecessor-version":[{"id":6239,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6165\/revisions\/6239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6169"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}