{"id":6189,"date":"2025-09-04T09:53:21","date_gmt":"2025-09-04T12:53:21","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6189"},"modified":"2025-09-04T09:53:23","modified_gmt":"2025-09-04T12:53:23","slug":"receita-antecipa-pagamento-do-ultimo-lote-da-restituicao-do-ir","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/09\/04\/receita-antecipa-pagamento-do-ultimo-lote-da-restituicao-do-ir\/","title":{"rendered":"Receita antecipa pagamento do \u00faltimo lote da restitui\u00e7\u00e3o do IR"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Ao contr\u00e1rio do previsto, n\u00e3o ser\u00e1 pago um quinto lote de restitui\u00e7\u00e3o do Imposto de Renda da Pessoa F\u00edsica, referente \u00e0s declara\u00e7\u00f5es do exerc\u00edcio 2025. Todas as restitui\u00e7\u00f5es entregues dentro do prazo e que n\u00e3o apresentaram inconsist\u00eancias j\u00e1 foram pagas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Secretaria da Receita Federal informou, na ter\u00e7a-feira, 02, que antecipou o pagamento e, ao contr\u00e1rio da previs\u00e3o de cinco lotes, que seria entre os meses de maio e setembro, a efici\u00eancia no processamento das declara\u00e7\u00f5es permitiu que os contribuintes que n\u00e3o apresentaram inconsist\u00eancias nos dados recebessem seus valores at\u00e9 o lote de agosto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o momento, mais de 22,6 milh\u00f5es de declara\u00e7\u00f5es de ajuste anual foram entregues.Foram pagos, neste ano, mais de R$ 36,6&nbsp;bilh\u00f5es em restitui\u00e7\u00f5es. Quem n\u00e3o recebeu a restitui\u00e7\u00e3o at\u00e9 o m\u00eas de agosto \u00e9 porque caiu na malha fina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esses contribuintes devem acessar o site da Receita, clicar em \u201cMeu Imposto de Renda\u201d para uma consulta completa da situa\u00e7\u00e3o da declara\u00e7\u00e3o, por meio do extrato do processamento. Havendo alguma pend\u00eancia, o contribuinte pode fazer a retifica\u00e7\u00e3o, corrigindo as informa\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9ditos: Lagartense.com.br<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Ao contr\u00e1rio do previsto, n\u00e3o ser\u00e1 pago um quinto lote de restitui\u00e7\u00e3o do Imposto de Renda da Pessoa F\u00edsica, referente \u00e0s declara\u00e7\u00f5es do exerc\u00edcio 2025. Todas as restitui\u00e7\u00f5es entregues dentro do prazo e que n\u00e3o apresentaram inconsist\u00eancias j\u00e1 foram pagas. A Secretaria da Receita Federal informou, na ter\u00e7a-feira, 02, que antecipou o pagamento e, ao [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/IMG_4909.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6189"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6189\/revisions"}],"predecessor-version":[{"id":6191,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6189\/revisions\/6191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6190"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}