{"id":6192,"date":"2025-09-04T09:55:54","date_gmt":"2025-09-04T12:55:54","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6192"},"modified":"2025-09-04T09:55:56","modified_gmt":"2025-09-04T12:55:56","slug":"bahia-goleia-confianca-por-4-a-1-na-final-da-copa-do-nordeste","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/09\/04\/bahia-goleia-confianca-por-4-a-1-na-final-da-copa-do-nordeste\/","title":{"rendered":"Bahia goleia Confian\u00e7a por 4 a 1 na final da Copa do Nordeste"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">O Bahia largou na frente na disputa pelo t\u00edtulo da Copa do Nordeste 2025. Jogando na noite desta quarta-feira (3), na Arena Batist\u00e3o, em Aracaju, o Esquadr\u00e3o de A\u00e7o venceu o Confian\u00e7a por 4 a 1 no jogo de ida da grande final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/imagens.f5news.com.br\/arquivos\/2025\/09\/bahia-copanordeste_656911756953963.jpeg\"><\/a>Let\u00edcia Martins \/ EC Bahia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os gols da equipe baiana foram marcados por Lucho, Willian Jos\u00e9, Nestor e Rezende. O time sergipano descontou com Ronald Camar\u00e3o, mas n\u00e3o conseguiu evitar a goleada em casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o resultado, o Bahia pode at\u00e9 perder por dois gols de diferen\u00e7a na partida de volta que, ainda assim, garante o trof\u00e9u. J\u00e1 o Confian\u00e7a precisa vencer por quatro gols de vantagem para ser campe\u00e3o no tempo normal ou por tr\u00eas para levar a decis\u00e3o para os p\u00eanaltis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesmo com a derrota, a torcida prolet\u00e1ria fez a festa e mostrou que acredita na virada fora de casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O confronto decisivo est\u00e1 marcado para o pr\u00f3ximo s\u00e1bado (6), na Arena Fonte Nova, em Salvador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O jogo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Tricolor n\u00e3o demorou a abrir o placar. Logo aos 4 minutos, Luciano Rodr\u00edguez aproveitou escanteio cobrado por Nestor e chutou de primeira para marcar um belo gol. Aos 27, Willian Jos\u00e9 completou cruzamento de Lucho e ampliou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na volta do intervalo, o Confian\u00e7a reagiu e diminuiu com Ronald Camar\u00e3o, aos 4 minutos. Mas a rea\u00e7\u00e3o durou pouco: aos 8, Rodrigo Nestor marcou em cobran\u00e7a de falta no \u00e2ngulo e deixou o Bahia novamente em vantagem confort\u00e1vel. O quarto veio aos 40, com Rezende, ap\u00f3s desvio em cobran\u00e7a de escanteio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: F5news<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>O Bahia largou na frente na disputa pelo t\u00edtulo da Copa do Nordeste 2025. Jogando na noite desta quarta-feira (3), na Arena Batist\u00e3o, em Aracaju, o Esquadr\u00e3o de A\u00e7o venceu o Confian\u00e7a por 4 a 1 no jogo de ida da grande final. Let\u00edcia Martins \/ EC Bahia Os gols da equipe baiana foram marcados [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/IMG_4910.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6192"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6192\/revisions"}],"predecessor-version":[{"id":6194,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6192\/revisions\/6194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6193"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}