{"id":6214,"date":"2025-09-08T17:34:26","date_gmt":"2025-09-08T20:34:26","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6214"},"modified":"2025-09-08T17:34:27","modified_gmt":"2025-09-08T20:34:27","slug":"tres-suspeitos-morrem-em-confronto-com-a-policia-em-propria","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/09\/08\/tres-suspeitos-morrem-em-confronto-com-a-policia-em-propria\/","title":{"rendered":"Tr\u00eas suspeitos morrem em confronto com a pol\u00edcia em Propri\u00e1"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Na manh\u00e3 desta segunda-feira (8), uma opera\u00e7\u00e3o conjunta no munic\u00edpio de Propri\u00e1, em Sergipe, resultou na morte de tr\u00eas suspeitos e na apreens\u00e3o de armas e drogas. A a\u00e7\u00e3o teve como objetivo combater o tr\u00e1fico interestadual de entorpecentes entre Alagoas e Sergipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/imagens.f5news.com.br\/arquivos\/2025\/06\/img_0386_336081751145614.png\"><\/a>PMSE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o delegado Albene J\u00fanior, respons\u00e1vel pela investiga\u00e7\u00e3o, o trabalho teve in\u00edcio h\u00e1 cerca de dois meses, ap\u00f3s a apreens\u00e3o de 25 quilos de maconha em Japoat\u00e3. \u00c0 \u00e9poca, os envolvidos n\u00e3o foram identificados, mas as apura\u00e7\u00f5es apontaram para o armazenamento da droga em Arapiraca, Alagoas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com base nas informa\u00e7\u00f5es, os policiais realizaram uma abordagem na entrada de Propri\u00e1. \u201cQuando deram voz de parada, os suspeitos inicialmente manifestaram a inten\u00e7\u00e3o de atender aos comandos, por\u00e9m, no segundo momento, dispararam com arma de fogo\u201d, relatou o delegado. Durante a troca de tiros, um policial militar foi atingido, mas socorrido rapidamente e n\u00e3o sofreu ferimentos graves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No revide, os tr\u00eas ocupantes do ve\u00edculo foram baleados e n\u00e3o resistiram, mesmo ap\u00f3s o socorro prestado. No carro, foram encontrados tr\u00eas armas de fogo \u2013 uma pistola e dois rev\u00f3lveres \u2013 al\u00e9m de cerca de dois quilos de maconha. As investiga\u00e7\u00f5es ainda apontaram que os suspeitos estariam ligados a um homic\u00eddio ocorrido em Arapiraca h\u00e1 15 dias.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta segunda-feira (8), uma opera\u00e7\u00e3o conjunta no munic\u00edpio de Propri\u00e1, em Sergipe, resultou na morte de tr\u00eas suspeitos e na apreens\u00e3o de armas e drogas. A a\u00e7\u00e3o teve como objetivo combater o tr\u00e1fico interestadual de entorpecentes entre Alagoas e Sergipe. PMSE Segundo o delegado Albene J\u00fanior, respons\u00e1vel pela investiga\u00e7\u00e3o, o trabalho teve in\u00edcio [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/IMG_4998.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6214"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6214\/revisions"}],"predecessor-version":[{"id":6216,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6214\/revisions\/6216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6215"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}