{"id":6371,"date":"2025-09-26T10:19:04","date_gmt":"2025-09-26T13:19:04","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6371"},"modified":"2025-09-29T17:37:34","modified_gmt":"2025-09-29T20:37:34","slug":"cadela-resgatada-apos-caso-de-zoofilia-e-adotada","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/09\/26\/cadela-resgatada-apos-caso-de-zoofilia-e-adotada\/","title":{"rendered":"Cadela resgatada ap\u00f3s caso de zoofilia \u00e9 adotada"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Com o apoio da Delegacia Especializada de Prote\u00e7\u00e3o Animal e Meio Ambiente (Depama), uma cadela resgatada ap\u00f3s ser v\u00edtima de maus-tratos, em Aracaju, foi oficialmente adotada na \u00faltima quinta-feira, 25, juntamente com seus cinco filhotes. A ado\u00e7\u00e3o foi realizada pela ativista Simone Almeida, moradora do munic\u00edpio de Est\u00e2ncia, com aux\u00edlio da Pol\u00edcia Civil e da protetora de animais Adriana Lima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O caso ganhou repercuss\u00e3o quando um v\u00eddeo, mostrando um idoso de 87 anos abusando do animal, circulou nas redes sociais. Ap\u00f3s dilig\u00eancias da Depama, o autor foi identificado e o&nbsp;inqu\u00e9rito policial aberto. Durante a investiga\u00e7\u00e3o, a equipe da delegacia tamb\u00e9m localizou a cadela, que vivia nas ruas e havia dado cria a cinco filhotes em uma \u00e1rea de matagal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir do encerramento do processo policial e os cuidados veterin\u00e1rios realizados, a cachorra foi considerada apta para ado\u00e7\u00e3o respons\u00e1vel. Nesta quinta, a ado\u00e7\u00e3o foi conclu\u00edda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSabemos que \u00e9 dif\u00edcil conseguir ado\u00e7\u00e3o para um animal adulto, e ainda mais quando tem filhotes. Mas a Simone aceitou adotar todos\u201d, afirmou a protetora Adriana Lima, que contribuiu com o desfecho positivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O delegado Fl\u00e1vio Albuquerque, titular da Depama, destacou que o encaminhamento dos animais para ado\u00e7\u00e3o fecha o ciclo de um caso que mobilizou a popula\u00e7\u00e3o. \u201cN\u00f3s estamos ent\u00e3o finalizando este ciclo com um fato positivo, que \u00e9 a ado\u00e7\u00e3o respons\u00e1vel. Eles seguem para uma ONG de Est\u00e2ncia, que os est\u00e1 acolhendo e esses animais agora ter\u00e3o uma vida melhor\u201d, concluiu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9ditos: Lagartense.com.br<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Com o apoio da Delegacia Especializada de Prote\u00e7\u00e3o Animal e Meio Ambiente (Depama), uma cadela resgatada ap\u00f3s ser v\u00edtima de maus-tratos, em Aracaju, foi oficialmente adotada na \u00faltima quinta-feira, 25, juntamente com seus cinco filhotes. A ado\u00e7\u00e3o foi realizada pela ativista Simone Almeida, moradora do munic\u00edpio de Est\u00e2ncia, com aux\u00edlio da Pol\u00edcia Civil e da [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/IMG_5391.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6371"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6371\/revisions"}],"predecessor-version":[{"id":6373,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6371\/revisions\/6373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6372"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}