{"id":6386,"date":"2025-09-27T13:30:03","date_gmt":"2025-09-27T16:30:03","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6386"},"modified":"2025-09-29T17:36:24","modified_gmt":"2025-09-29T20:36:24","slug":"caso-sargento-bio-volta-a-repercutir-na-imprensa-apos-denuncia-da-filha-ganhar-destaque-nas-redes","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/09\/27\/caso-sargento-bio-volta-a-repercutir-na-imprensa-apos-denuncia-da-filha-ganhar-destaque-nas-redes\/","title":{"rendered":"Caso Sargento Bio volta a repercutir na imprensa ap\u00f3s den\u00fancia da filha ganhar destaque nas redes"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A den\u00fancia feita por Sheila Bio, filha do sargento Roberto Carlos, sobre uma suposta tentativa de silenciamento pela defesa do r\u00e9u, repercutiu em diversos ve\u00edculos de imprensa do estado. A cobertura da Revista Realce foi seguida por portais, r\u00e1dios e programas de televis\u00e3o, ampliando ainda mais a press\u00e3o em torno do julgamento marcado para 30 de outubro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com v\u00eddeos e postagens que j\u00e1 acumulam milhares de visualiza\u00e7\u00f5es, Sheila se tornou uma voz ativa no processo, levando o debate para al\u00e9m dos autos judiciais. Esse engajamento digital foi apontado pela defesa como motivo para o pedido de desaforamento, mas, na pr\u00e1tica, acabou projetando o caso para um patamar ainda maior de visibilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na imprensa, o ponto central da discuss\u00e3o gira em torno da legitimidade da manifesta\u00e7\u00e3o da fam\u00edlia diante de um crime de grande repercuss\u00e3o social. Para analistas, a tentativa de transferir o j\u00fari para outra comarca pode ser interpretada como uma estrat\u00e9gia para reduzir o peso da press\u00e3o popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O resultado imediato \u00e9 o fortalecimento da mobiliza\u00e7\u00e3o em defesa da mem\u00f3ria do sargento.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A den\u00fancia feita por Sheila Bio, filha do sargento Roberto Carlos, sobre uma suposta tentativa de silenciamento pela defesa do r\u00e9u, repercutiu em diversos ve\u00edculos de imprensa do estado. A cobertura da Revista Realce foi seguida por portais, r\u00e1dios e programas de televis\u00e3o, ampliando ainda mais a press\u00e3o em torno do julgamento marcado para 30 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/09\/5de64fe1-612c-46b9-b7b8-f06ae99a7cb8.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6386"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6386\/revisions"}],"predecessor-version":[{"id":6388,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6386\/revisions\/6388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6387"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}