{"id":6422,"date":"2025-10-03T10:01:05","date_gmt":"2025-10-03T13:01:05","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6422"},"modified":"2025-10-03T10:01:06","modified_gmt":"2025-10-03T13:01:06","slug":"adema-interdita-producao-nao-licenciada-de-farinha-de-tapioca-em-salgado","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/10\/03\/adema-interdita-producao-nao-licenciada-de-farinha-de-tapioca-em-salgado\/","title":{"rendered":"Adema interdita produ\u00e7\u00e3o n\u00e3o licenciada de farinha de tapioca em Salgado"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">No munic\u00edpio de Salgado, centro-sul sergipano, a equipe de fiscaliza\u00e7\u00e3o da Administra\u00e7\u00e3o Estadual do Meio Ambiente (Adema) confirmou den\u00fancia recebida sobre o despejo ilegal de efluentes em um riacho por um estabelecimento n\u00e3o licenciado produtor de farinha de tapioca. Na primeira tentativa de abordagem, a equipe da Adema foi impedida de entrar no local, retornando posteriormente com refor\u00e7o da Companhia Independente de Pol\u00edcia Ambiental (CIPAm\/PM\/SE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No local, foram encontradas condi\u00e7\u00f5es prec\u00e1rias de produ\u00e7\u00e3o e descarte de res\u00edduos s\u00f3lidos e l\u00edquidos, levando contaminantes para a \u00e1rea do entorno, incluindo um riacho. O empreendimento produzia, aproximadamente, dois mil quilos de farinha de tapioca por dia e armazenava at\u00e9 oito mil quilos sem observ\u00e2ncia das normas ambientais. Os funcion\u00e1rios que l\u00e1 estavam foram encontrados trabalhando sem Equipamentos de Prote\u00e7\u00e3o Individual (EPIs) e sem as m\u00ednimas condi\u00e7\u00f5es sanit\u00e1rias e de seguran\u00e7a. Os fiscais da Adema realizaram, ent\u00e3o, a imediata interdi\u00e7\u00e3o do local, que teve suas opera\u00e7\u00f5es paralisadas com a lacra\u00e7\u00e3o do maquin\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O gerente de Fiscaliza\u00e7\u00e3o da Adema, Alo\u00edzio Franca, explica as medidas que ser\u00e3o adotadas a partir do flagrante. \u201cAp\u00f3s a paralisa\u00e7\u00e3o imediata da atividade e interdi\u00e7\u00e3o do local, ser\u00e1 lavrado o auto de infra\u00e7\u00e3o pela opera\u00e7\u00e3o sem licen\u00e7a, pela obstru\u00e7\u00e3o da fiscaliza\u00e7\u00e3o e pelos danos ambientais produzidos. Caso queira retomar a opera\u00e7\u00e3o, o empreendedor precisar\u00e1 procurar o setor de Licenciamento da Adema para buscar se regularizar, caso seja poss\u00edvel, mas com certeza precisar\u00e1 fazer muitas adequa\u00e7\u00f5es\u201d, detalha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele refor\u00e7a, ainda, a import\u00e2ncia da regulariza\u00e7\u00e3o ambiental de todos os empreendimentos produtivos que possuam potencial poluidor ou que se utilizem de recursos naturais. \u201cEstar com a licen\u00e7a em dia, al\u00e9m de garantir a correta execu\u00e7\u00e3o da atividade, tamb\u00e9m \u00e9 essencial para a preven\u00e7\u00e3o de danos ao meio ambiente\u201d, conclui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como denunciar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Administra\u00e7\u00e3o Estadual do Meio Ambiente segue incentivando a popula\u00e7\u00e3o a realizar novas den\u00fancias, contribuindo para o combate a infra\u00e7\u00f5es e crimes ambientais. Por meio do e-mail denuncia@adema.se.gov.br \u00e9 poss\u00edvel denunciar casos de descarte irregular de res\u00edduos s\u00f3lidos e efluentes, tr\u00e1fico ou cria\u00e7\u00e3o ilegal de animais silvestres, desmatamento, queimadas, polui\u00e7\u00e3o, empreendimentos n\u00e3o licenciados, dentre outras infra\u00e7\u00f5es ambientais. As den\u00fancias tamb\u00e9m podem ser feitas presencialmente na sede da Adema, de segunda a sexta-feira, das 7h \u00e0s 13h, ou pelo telefone\u00a0(79) 3198-7152.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9ditos: Lagartense.com.br<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>No munic\u00edpio de Salgado, centro-sul sergipano, a equipe de fiscaliza\u00e7\u00e3o da Administra\u00e7\u00e3o Estadual do Meio Ambiente (Adema) confirmou den\u00fancia recebida sobre o despejo ilegal de efluentes em um riacho por um estabelecimento n\u00e3o licenciado produtor de farinha de tapioca. Na primeira tentativa de abordagem, a equipe da Adema foi impedida de entrar no local, retornando [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":6423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/IMG_5560.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6422"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6422\/revisions"}],"predecessor-version":[{"id":6424,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6422\/revisions\/6424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6423"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}