{"id":6425,"date":"2025-10-03T10:03:44","date_gmt":"2025-10-03T13:03:44","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6425"},"modified":"2025-10-03T10:03:46","modified_gmt":"2025-10-03T13:03:46","slug":"secretaria-de-saude-alerta-municipios-sobre-identificacao-de-casos-de-intoxicacao-por-metanol-em-sergipe","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/10\/03\/secretaria-de-saude-alerta-municipios-sobre-identificacao-de-casos-de-intoxicacao-por-metanol-em-sergipe\/","title":{"rendered":"Secretaria de Sa\u00fade alerta munic\u00edpios sobre identifica\u00e7\u00e3o de casos de intoxica\u00e7\u00e3o por metanol em Sergipe"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Secretaria de Estado da Sa\u00fade (SES) encaminhou aos munic\u00edpios sergipanos um alerta epidemiol\u00f3gico para instruir os profissionais de sa\u00fade sobre a identifica\u00e7\u00e3o de casos de intoxica\u00e7\u00e3o por metanol. A medida atende a recomenda\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade (MS).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O alerta acontece ap\u00f3s diferentes estados registrarem casos suspeitos, bem como confirma\u00e7\u00e3o de mortes por intoxica\u00e7\u00e3o de metanol em bebidas alco\u00f3licas adulteradas. A situa\u00e7\u00e3o \u00e9 caracterizada como um Evento de Sa\u00fade P\u00fablica (ESP).\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O diretor da Vigil\u00e2ncia Sanit\u00e1ria, Marco Aur\u00e9lio, explicou que, apesar de Sergipe n\u00e3o ter nenhum caso suspeito, os profissionais de sa\u00fade devem ficar atentos a sinais e sintomas como&nbsp;dor abdominal, vis\u00e3o adulterada, confus\u00e3o mental, convuls\u00f5es, n\u00e1usea, quadro de gastrite e embriaguez apresentados ap\u00f3s 12 horas da ingest\u00e3o de bebida alco\u00f3lica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso algum paciente apresente os sintomas de intoxica\u00e7\u00e3o por metanol, os profissionais de sa\u00fade devem informar, em at\u00e9 24 horas, ao Centro de Informa\u00e7\u00f5es Estrat\u00e9gicas de Vigil\u00e2ncia em Sa\u00fade de Sergipe (Cievs\/SE) por meio do\u00a0e-Notifica Cievs\u00a0ou pelo Disque Notifica (79-99191-5838).\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a notifica\u00e7\u00e3o deve ser registrada no Sistema de Informa\u00e7\u00e3o de Agravos de Notifica\u00e7\u00e3o (Sinan), sob o agravo Intoxica\u00e7\u00e3o Ex\u00f3gena, e encaminhada \u00e0 Vigil\u00e2ncia Epidemiol\u00f3gica do munic\u00edpio onde foi realizado o atendimento\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Sa\u00fade (SES) encaminhou aos munic\u00edpios sergipanos um alerta epidemiol\u00f3gico para instruir os profissionais de sa\u00fade sobre a identifica\u00e7\u00e3o de casos de intoxica\u00e7\u00e3o por metanol. A medida atende a recomenda\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade (MS).&nbsp; O alerta acontece ap\u00f3s diferentes estados registrarem casos suspeitos, bem como confirma\u00e7\u00e3o de mortes por intoxica\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":6426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/IMG_5561.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6425"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6425\/revisions"}],"predecessor-version":[{"id":6427,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6425\/revisions\/6427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6426"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}