{"id":6439,"date":"2025-10-07T10:08:52","date_gmt":"2025-10-07T13:08:52","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6439"},"modified":"2025-10-07T10:08:54","modified_gmt":"2025-10-07T13:08:54","slug":"suspeito-e-preso-com-arma-e-objetos-furtados-apos-ser-contido-por-morador-em-ribeiropolis","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/10\/07\/suspeito-e-preso-com-arma-e-objetos-furtados-apos-ser-contido-por-morador-em-ribeiropolis\/","title":{"rendered":"Suspeito \u00e9 preso com arma e objetos furtados ap\u00f3s ser contido por morador em Ribeir\u00f3polis"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um homem foi preso em flagrante na manh\u00e3 de ontem, segunda-feira (6), no povoado Esteios, em Ribeir\u00f3polis, suspeito de invadir uma resid\u00eancia e furtar diversos objetos. A pris\u00e3o foi resultado de uma a\u00e7\u00e3o conjunta entre policiais civis da Delegacia de Ribeir\u00f3polis e militares da 3\u00aa Companhia do 3\u00ba Batalh\u00e3o de Pol\u00edcia Militar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com informa\u00e7\u00f5es da pol\u00edcia, o crime foi interrompido pelo pr\u00f3prio morador da casa, que conseguiu imobilizar o suspeito at\u00e9 a chegada das equipes policiais. Com o homem, foram encontrados uma arma de fogo, muni\u00e7\u00f5es, dinheiro em esp\u00e9cie e parte dos itens levados da resid\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O suspeito n\u00e3o possu\u00eda autoriza\u00e7\u00e3o legal para portar a arma e, por isso, foi autuado por furto qualificado e porte ilegal de arma de fogo. O caso foi registrado na Delegacia Regional de Itabaiana. A Pol\u00edcia Civil segue com as investiga\u00e7\u00f5es para apurar se o homem tem liga\u00e7\u00e3o com outros furtos ocorridos na regi\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Portal Itnet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um homem foi preso em flagrante na manh\u00e3 de ontem, segunda-feira (6), no povoado Esteios, em Ribeir\u00f3polis, suspeito de invadir uma resid\u00eancia e furtar diversos objetos. A pris\u00e3o foi resultado de uma a\u00e7\u00e3o conjunta entre policiais civis da Delegacia de Ribeir\u00f3polis e militares da 3\u00aa Companhia do 3\u00ba Batalh\u00e3o de Pol\u00edcia Militar. De acordo com [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":6440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/IMG_5621.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6439"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6439\/revisions"}],"predecessor-version":[{"id":6441,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6439\/revisions\/6441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6440"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}