{"id":6459,"date":"2025-10-08T17:43:19","date_gmt":"2025-10-08T20:43:19","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6459"},"modified":"2025-10-08T17:43:20","modified_gmt":"2025-10-08T20:43:20","slug":"governo-de-sergipe-fortalece-producao-leiteira-e-impulsiona-a-agropecuaria-no-estado","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/10\/08\/governo-de-sergipe-fortalece-producao-leiteira-e-impulsiona-a-agropecuaria-no-estado\/","title":{"rendered":"Governo de Sergipe fortalece produ\u00e7\u00e3o leiteira e impulsiona a agropecu\u00e1ria no estado"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\"><em>Com pol\u00edticas de incentivo, cr\u00e9dito rural e investimentos em infraestrutura, o estado amplia a produ\u00e7\u00e3o leiteira e estimula o desenvolvimento do campo<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O resultado da Pesquisa da Pecu\u00e1ria Municipal (PPM) 2024, do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), confirma o avan\u00e7o da pecu\u00e1ria em Sergipe e o protagonismo do setor leiteiro. O levantamento mostra que a produ\u00e7\u00e3o de leite representa 86% dos quase R$ 2 bilh\u00f5es do valor total da produ\u00e7\u00e3o pecu\u00e1ria estadual. Os munic\u00edpios de Po\u00e7o Redondo, Porto da Folha e Nossa Senhora da Gl\u00f3ria, localizados no alto sert\u00e3o sergipano, figuram entre os 20 maiores produtores do pa\u00eds, sendo respons\u00e1veis por quase metade dos 678 milh\u00f5es de litros produzidos no estado em 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse desempenho \u00e9 resultado direto das pol\u00edticas p\u00fablicas e do trabalho integrado entre os produtores e o Governo de Sergipe, que tem investido em moderniza\u00e7\u00e3o e assist\u00eancia t\u00e9cnica. Programas de melhoramento gen\u00e9tico, inova\u00e7\u00e3o tecnol\u00f3gica e capacita\u00e7\u00e3o dos criadores t\u00eam elevado a produtividade e a qualidade do leite sergipano, fortalecendo a economia do interior e ampliando as oportunidades para os pequenos produtores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incentivo \u00e0 produ\u00e7\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre as iniciativas que impulsionam o setor est\u00e1 a amplia\u00e7\u00e3o do Servi\u00e7o de Inspe\u00e7\u00e3o Estadual da Empresa de Desenvolvimento Agropecu\u00e1rio de Sergipe (Emdagro) para a \u00e1rea de leite e derivados, permitindo que produtores sergipanos tenham valida\u00e7\u00e3o pelo Sistema Brasileiro de Inspe\u00e7\u00e3o de Produtos de Origem Animal (Sisbi-POA) e possam comercializar seus produtos em outros estados. Outro destaque \u00e9 o Programa Sementes do Futuro, que fomenta a produ\u00e7\u00e3o de milho e palma forrageira, bases da alimenta\u00e7\u00e3o animal, com a doa\u00e7\u00e3o de mais de 500 toneladas de sementes de milho e 648 mil raquetes de palma a pequenos produtores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O melhoramento gen\u00e9tico tamb\u00e9m \u00e9 prioridade. Entre 2023 e 2024, o Governo de Sergipe realizou 1.054 insemina\u00e7\u00f5es artificiais gratuitas, por meio da Insemina\u00e7\u00e3o Artificial por Tempo Fixo (IATF). Essa a\u00e7\u00e3o, somada \u00e0 assist\u00eancia t\u00e9cnica e doa\u00e7\u00e3o de kits de ordenha oferecidos pela Emdagro, tem melhorado o desempenho dos rebanhos e garantido maior rentabilidade ao produtor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra pol\u00edtica de destaque \u00e9 o Programa de Aquisi\u00e7\u00e3o de Alimentos Leite (PAA Leite), que compra 90 mil litros de leite por m\u00eas de produtores locais e j\u00e1 distribuiu mais de um milh\u00e3o de litros a fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade. Iniciativas como o Programa M\u00e3o Amiga Bacia Leiteira, que beneficia mais de 3 mil pequenos criadores, e os incentivos fiscais do Programa Sergipano de Desenvolvimento Industrial (PSDI), voltados \u00e0s ind\u00fastrias de latic\u00ednios, completam o conjunto de a\u00e7\u00f5es voltadas ao fortalecimento da cadeia leiteira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para garantir o escoamento da produ\u00e7\u00e3o, o Governo do Estado tem investido fortemente em infraestrutura e mobilidade rural. Sergipe \u00e9 o 1\u00ba estado do Nordeste em qualidade de rodovias, o que facilita o transporte da produ\u00e7\u00e3o, reduz custos e melhora a competitividade. A Adutora do Leite, em fase de estudo, deve consolidar ainda mais esse crescimento, com investimento de R$ 250 milh\u00f5es para levar \u00e1gua do Rio S\u00e3o Francisco a munic\u00edpios do alto sert\u00e3o, como Po\u00e7o Redondo, Nossa Senhora da Gl\u00f3ria e Monte Alegre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desenvolvimento no campo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da cadeia do leite, o Governo de Sergipe tem atuado de forma ampla para fortalecer toda a agropecu\u00e1ria. A Adutora do Curralinho, em Porto da Folha, e as 1.223 a\u00e7\u00f5es de limpeza e constru\u00e7\u00e3o de barragens de terra, executadas pela Companhia de Desenvolvimento Regional de Sergipe (Coderse), j\u00e1 somam R$ 7,5 milh\u00f5es em investimentos voltados \u00e0 seguran\u00e7a h\u00eddrica no campo. O projeto Sert\u00e3o Vivo, com aporte de R$ 150 milh\u00f5es, vai beneficiar 38 mil fam\u00edlias em 30 munic\u00edpios, promovendo acesso \u00e0 \u00e1gua e mitiga\u00e7\u00e3o dos efeitos das mudan\u00e7as clim\u00e1ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Programas como Rode Bem, CNH Social e CNH Caminhoneiro refor\u00e7am o compromisso da gest\u00e3o com os trabalhadores rurais, garantindo isen\u00e7\u00e3o de Imposto sobre a Propriedade de Ve\u00edculos Automotores (IPVA), habilita\u00e7\u00e3o gratuita e oportunidades de qualifica\u00e7\u00e3o profissional. Essas a\u00e7\u00f5es asseguram dignidade, mobilidade e seguran\u00e7a para quem vive e trabalha no campo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"568\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/4ad5440e-48e4-451c-9064-2bc19f0b48b6-1024x568.jpeg\" alt=\"\" class=\"wp-image-6460\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/4ad5440e-48e4-451c-9064-2bc19f0b48b6-1024x568.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/4ad5440e-48e4-451c-9064-2bc19f0b48b6-300x166.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/4ad5440e-48e4-451c-9064-2bc19f0b48b6-768x426.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/4ad5440e-48e4-451c-9064-2bc19f0b48b6.jpeg 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Com pol\u00edticas de incentivo, cr\u00e9dito rural e investimentos em infraestrutura, o estado amplia a produ\u00e7\u00e3o leiteira e estimula o desenvolvimento do campo O resultado da Pesquisa da Pecu\u00e1ria Municipal (PPM) 2024, do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), confirma o avan\u00e7o da pecu\u00e1ria em Sergipe e o protagonismo do setor leiteiro. O levantamento mostra [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":6461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/d742ce37-0c1d-4189-8de3-3f53ed7c9068.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6459"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6459\/revisions"}],"predecessor-version":[{"id":6462,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6459\/revisions\/6462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6461"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}