{"id":6536,"date":"2025-10-23T11:13:54","date_gmt":"2025-10-23T14:13:54","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6536"},"modified":"2025-11-04T17:44:51","modified_gmt":"2025-11-04T20:44:51","slug":"carroceiro-e-morto-a-tiros-apos-briga-no-centro-de-itabaiana","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/10\/23\/carroceiro-e-morto-a-tiros-apos-briga-no-centro-de-itabaiana\/","title":{"rendered":"Carroceiro \u00e9 morto a tiros ap\u00f3s briga no centro de Itabaiana"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um homem foi morto a tiros no Mercado da Carne de Itabaiana, na manh\u00e3 desta quinta-feira, 23. A Pol\u00edcia Militar foi acionada, ap\u00f3s relatos de tumulto no local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao chegar ao ponto indicado, a guarni\u00e7\u00e3o confirmou o crime e recebeu informa\u00e7\u00f5es de que a v\u00edtima havia se envolvido em uma briga com o suspeito, momentos antes do homic\u00eddio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A \u00e1rea foi isolada para preserva\u00e7\u00e3o da cena e equipes da Criminal\u00edstica foram acionadas para os procedimentos necess\u00e1rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As circunst\u00e2ncias do crime ser\u00e3o investigadas pela Pol\u00edcia Civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um homem foi morto a tiros no Mercado da Carne de Itabaiana, na manh\u00e3 desta quinta-feira, 23. A Pol\u00edcia Militar foi acionada, ap\u00f3s relatos de tumulto no local. Ao chegar ao ponto indicado, a guarni\u00e7\u00e3o confirmou o crime e recebeu informa\u00e7\u00f5es de que a v\u00edtima havia se envolvido em uma briga com o suspeito, momentos [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":6537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/IMG_5965.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6536"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6536\/revisions"}],"predecessor-version":[{"id":6538,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6536\/revisions\/6538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6537"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}