{"id":6577,"date":"2025-10-30T15:08:58","date_gmt":"2025-10-30T18:08:58","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6577"},"modified":"2025-11-04T18:25:20","modified_gmt":"2025-11-04T21:25:20","slug":"policia-militar-prende-suspeito-de-tentativa-de-homicidio-em-lagarto","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/10\/30\/policia-militar-prende-suspeito-de-tentativa-de-homicidio-em-lagarto\/","title":{"rendered":"Pol\u00edcia Militar prende suspeito de tentativa de homic\u00eddio em Lagarto"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Na manh\u00e3 desta quinta-feira, 30, policiais do 7\u00ba Batalh\u00e3o de Pol\u00edcia Militar (7\u00ba BPM) prenderem em flagrante um homem armado suspeito de tentativa de homic\u00eddio, em Lagarto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante patrulhamento de rotina, policiais foram acionados por uma mulher que, muito nervosa, informou que um homem havia acabado de esfaquear outra pessoa e danificado os pneus de uma motocicleta utilizando uma faca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De posse das informa\u00e7\u00f5es, a guarni\u00e7\u00e3o iniciou dilig\u00eancias e localizou o suspeito nas proximidades de um estabelecimento comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao ser abordado, o homem confessou o ato. Durante a busca pessoal, foram encontrados com ele uma faca, possivelmente utilizada no crime, e uma arma de fogo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante dos fatos, o suspeito recebeu voz de pris\u00e3o em flagrante. No entanto, passou a resistir \u00e0 a\u00e7\u00e3o policial, proferindo amea\u00e7as e danificando a estrutura da viatura, o que exigiu o uso de t\u00e9cnicas de contens\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, o suspeito foi conduzido \u00e0 Delegacia Regional de Lagarto para a ado\u00e7\u00e3o das medidas cab\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9ditos: Lagartense.com.br<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quinta-feira, 30, policiais do 7\u00ba Batalh\u00e3o de Pol\u00edcia Militar (7\u00ba BPM) prenderem em flagrante um homem armado suspeito de tentativa de homic\u00eddio, em Lagarto. Durante patrulhamento de rotina, policiais foram acionados por uma mulher que, muito nervosa, informou que um homem havia acabado de esfaquear outra pessoa e danificado os pneus de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6578,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/10\/IMG_6117.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6577"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6577\/revisions"}],"predecessor-version":[{"id":6579,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6577\/revisions\/6579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6578"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}