{"id":6629,"date":"2025-11-06T15:03:57","date_gmt":"2025-11-06T18:03:57","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6629"},"modified":"2025-11-06T15:03:58","modified_gmt":"2025-11-06T18:03:58","slug":"professora-de-estetica-e-indiciada-por-matar-namorado-a-tesouradas-e-enterrar-corpo-no-quintal-de-casa","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/11\/06\/professora-de-estetica-e-indiciada-por-matar-namorado-a-tesouradas-e-enterrar-corpo-no-quintal-de-casa\/","title":{"rendered":"Professora de est\u00e9tica \u00e9 indiciada por matar namorado a tesouradas e enterrar corpo no quintal de casa"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A professora de est\u00e9tica Jussara Luzia Fernandes, de 62 anos,\u00a0foi indiciada pela morte do namorado Alex Sandro da Silva Rocha, de 21 anos, em Bebedouro (SP). Segundo o delegado Jo\u00e3o Vitor Silv\u00e9rio, o inqu\u00e9rito foi enviado ao Minist\u00e9rio P\u00fablico (MP), que decidir\u00e1 se a den\u00fancia ser\u00e1 ou n\u00e3o encaminhada \u00e0 Justi\u00e7a.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com Silv\u00e9rio, ela responde por homic\u00eddio e oculta\u00e7\u00e3o de cad\u00e1ver. Alex Sandro, que \u00e9 do estado de Sergipe, foi morto no dia 22 de outubro, na casa onde vivia com a namorada. Ele levou 72 tesouradas e teve o corpo enterrado no quintal do im\u00f3vel.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jussara est\u00e1 presa preventivamente e confessou o assassinato. A defesa dela n\u00e3o foi localizada para comentar o assunto at\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A professora de est\u00e9tica Jussara Luzia Fernandes, de 62 anos,\u00a0foi indiciada pela morte do namorado Alex Sandro da Silva Rocha, de 21 anos, em Bebedouro (SP). Segundo o delegado Jo\u00e3o Vitor Silv\u00e9rio, o inqu\u00e9rito foi enviado ao Minist\u00e9rio P\u00fablico (MP), que decidir\u00e1 se a den\u00fancia ser\u00e1 ou n\u00e3o encaminhada \u00e0 Justi\u00e7a.\u00a0 De acordo com Silv\u00e9rio, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/11\/IMG_6247.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6629"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6629\/revisions"}],"predecessor-version":[{"id":6631,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6629\/revisions\/6631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6630"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}