{"id":6675,"date":"2025-11-17T15:57:22","date_gmt":"2025-11-17T18:57:22","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6675"},"modified":"2025-12-15T18:12:17","modified_gmt":"2025-12-15T21:12:17","slug":"queda-de-furtos-e-prisoes-marcam-balanco-de-seguranca-do-pre-caju-2025","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/11\/17\/queda-de-furtos-e-prisoes-marcam-balanco-de-seguranca-do-pre-caju-2025\/","title":{"rendered":"Queda de furtos e pris\u00f5es marcam balan\u00e7o de seguran\u00e7a do Pr\u00e9-Caju 2025"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">O Pr\u00e9-Caju 2025 terminou com redu\u00e7\u00e3o de ocorr\u00eancias criminais e aumento da efetividade policial, segundo balan\u00e7o divulgado pela Secretaria da Seguran\u00e7a P\u00fablica (SSP). A opera\u00e7\u00e3o integrada&nbsp;<strong>mobilizou mais de 2,4 mil profissionais das pol\u00edcias Militar<\/strong>, Civil, Cient\u00edfica e do Corpo de Bombeiros durante os tr\u00eas dias de festa na Orla da Atalaia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quatro mandados de pris\u00e3o foram cumpridos, al\u00e9m de tr\u00eas flagrantes por furto de celulares \u2014 tipo de ocorr\u00eancia que, embora ainda frequente, apresentou queda expressiva em rela\u00e7\u00e3o ao ano anterior. Segundo a Pol\u00edcia Civil, foram pouco mais de 200 boletins registrados, contra mais de 500 em 2024. Tamb\u00e9m houve redu\u00e7\u00e3o nos furtos de celulares, que passaram de mais de 400 para 151, e nos roubos de ve\u00edculos, que ca\u00edram de cinco para um.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para garantir o funcionamento da \u00e1rea investigativa, a Delegacia de Turismo (Detur) atuou em regime de plant\u00e3o e contou com o apoio de unidades como a Divis\u00e3o de Intelig\u00eancia (Dipol) e a Decon. A instala\u00e7\u00e3o de um Centro de Comando agilizou an\u00e1lises e cruzamento de informa\u00e7\u00f5es, o que, segundo a coordenadora das delegacias da capital, Rosana Freitas, foi decisivo para o resultado. \u201cHouve um incremento significativo no trabalho investigativo, possibilitando sete pris\u00f5es e uma queda geral nas ocorr\u00eancias\u201d, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na parte ostensiva, a Pol\u00edcia Militar empregou cerca de 1,8 mil agentes com apoio de viaturas, motocicletas, drones e da aeronave do Grupamento T\u00e1tico A\u00e9reo (GTA). O policiamento interno do circuito foi refor\u00e7ado sem preju\u00edzo das demais \u00e1reas da capital e do interior. Bases m\u00f3veis, patrulhamento a\u00e9reo, tropa de choque e unidades especializadas compuseram o esquema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Cient\u00edfica realizou an\u00e1lises f\u00edsico-qu\u00edmicas em bebidas, inspe\u00e7\u00e3o de barracas, camarotes e restaurantes, mas n\u00e3o encontrou adultera\u00e7\u00f5es. Para o coordenador-geral de per\u00edcias, Victor Barros, a atua\u00e7\u00e3o pr\u00e9via foi determinante: \u201cPercorremos todo o circuito e n\u00e3o registramos nenhuma bebida irregular\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>O Pr\u00e9-Caju 2025 terminou com redu\u00e7\u00e3o de ocorr\u00eancias criminais e aumento da efetividade policial, segundo balan\u00e7o divulgado pela Secretaria da Seguran\u00e7a P\u00fablica (SSP). A opera\u00e7\u00e3o integrada&nbsp;mobilizou mais de 2,4 mil profissionais das pol\u00edcias Militar, Civil, Cient\u00edfica e do Corpo de Bombeiros durante os tr\u00eas dias de festa na Orla da Atalaia. Quatro mandados de pris\u00e3o [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6676,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/11\/IMG_6441.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6675"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6675\/revisions"}],"predecessor-version":[{"id":6677,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6675\/revisions\/6677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6676"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}