{"id":6681,"date":"2025-11-18T11:09:49","date_gmt":"2025-11-18T14:09:49","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6681"},"modified":"2025-12-15T18:11:21","modified_gmt":"2025-12-15T21:11:21","slug":"inss-libera-pedido-de-devolucao-de-descontos-indevidos-em-beneficios-de-falecidos","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/11\/18\/inss-libera-pedido-de-devolucao-de-descontos-indevidos-em-beneficios-de-falecidos\/","title":{"rendered":"INSS libera pedido de devolu\u00e7\u00e3o de descontos indevidos em benef\u00edcios de falecidos"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">O Governo Federal inicia, nesta quarta-feira (19), o processo para que herdeiros e pensionistas solicitem a devolu\u00e7\u00e3o de valores descontados indevidamente por entidades associativas em benef\u00edcios de pessoas j\u00e1 falecidas. Entre mar\u00e7o de 2020 e mar\u00e7o de 2025, cerca de 800 mil pessoas falecidas tiveram valores descontados irregularmente de seus benef\u00edcios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Como solicitar a devolu\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para pensionistas<\/strong><br>Quando o benef\u00edcio de falecido gerou Pens\u00e3o por Morte, o pedido pode ser feito pelo titular da pens\u00e3o atrav\u00e9s do Meu INSS, da Central 135, do PrevBarco ou em uma ag\u00eancia dos Correios. O valor recuperado ser\u00e1 dividido entre todos os pensionistas do benef\u00edcio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para herdeiros<\/strong><br>No caso de benef\u00edcios de pessoas falecidas que n\u00e3o geraram Pens\u00e3o por Morte, \u00e9 necess\u00e1rio primeiro que a condi\u00e7\u00e3o de herdeiro seja reconhecida pelo INSS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Passo 1 \u2013 Reconhecimento como herdeiro<\/strong><br>No Meu INSS, acesse &#8220;Consultar Descontos de Entidades Associativas&#8221; e escolha a op\u00e7\u00e3o &#8220;Consultar Descontos &#8211; Benef\u00edcio de Pessoa Falecida &#8211; para o Sucessor ou Herdeiro&#8221;. Depois, clique em &#8220;Pedir An\u00e1lise&#8221;.<br>Documentos necess\u00e1rios:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Escritura P\u00fablica ou Alvar\u00e1 Judicial com autoriza\u00e7\u00e3o para contesta\u00e7\u00e3o em nome dos sucessores.<\/li>\n\n\n\n<li>Documento de identifica\u00e7\u00e3o e comprovante de endere\u00e7o do solicitante.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Em caso de d\u00favidas, \u00e9 poss\u00edvel ligar para a Central 135.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Passo 2 \u2013 Solicita\u00e7\u00e3o da devolu\u00e7\u00e3o<\/strong><br>Ap\u00f3s o reconhecimento como herdeiro, a devolu\u00e7\u00e3o pode ser solicitada pelo Meu INSS, Central 135, PrevBarco ou ag\u00eancias dos Correios.<br>No Meu INSS, acesse:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&#8220;Consultar Pedidos&#8221;<\/li>\n\n\n\n<li>Localize &#8220;Cadastrar Sucessor\/Herdeiro &#8211; Descontos de Entidades Associativas&#8221;<\/li>\n\n\n\n<li>Clique em &#8220;Consultar Descontos de Entidades Associativas&#8221;<\/li>\n\n\n\n<li>Confira os descontos e indique se foram autorizados ou n\u00e3o<\/li>\n\n\n\n<li>Preencha os dados e clique em &#8220;Enviar Declara\u00e7\u00e3o&#8221;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O valor devolvido ser\u00e1 dividido entre todos os sucessores ou herdeiros do benef\u00edcio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Portal Itnet <\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>O Governo Federal inicia, nesta quarta-feira (19), o processo para que herdeiros e pensionistas solicitem a devolu\u00e7\u00e3o de valores descontados indevidamente por entidades associativas em benef\u00edcios de pessoas j\u00e1 falecidas. Entre mar\u00e7o de 2020 e mar\u00e7o de 2025, cerca de 800 mil pessoas falecidas tiveram valores descontados irregularmente de seus benef\u00edcios. Como solicitar a devolu\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6682,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/11\/IMG_6457.webp","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6681"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6681\/revisions"}],"predecessor-version":[{"id":6683,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6681\/revisions\/6683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6682"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}