{"id":6703,"date":"2025-11-25T14:00:42","date_gmt":"2025-11-25T17:00:42","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6703"},"modified":"2025-12-15T18:43:33","modified_gmt":"2025-12-15T21:43:33","slug":"mulher-e-presa-suspeita-de-participar-de-roubo-a-motorista-de-aplicativo","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/11\/25\/mulher-e-presa-suspeita-de-participar-de-roubo-a-motorista-de-aplicativo\/","title":{"rendered":"Mulher \u00e9 presa suspeita de participar de roubo a motorista de aplicativo"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Civil, por meio da Divis\u00e3o de Roubos e Furtos de Ve\u00edculos (DRFV), prendeu na manh\u00e3 da segunda-feira, 24, uma mulher de 20 anos suspeita de integrar o grupo respons\u00e1vel pelo roubo de um ve\u00edculo e de um aparelho celular de um motorista de aplicativo no bairro Coqueiral, em Aracaju. O crime ocorreu em maio deste ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a delegada Michele Ara\u00fajo, diretora da DRFV, a investiga\u00e7\u00e3o identificou que a a\u00e7\u00e3o criminosa foi praticada por quatro pessoas, organizadas em dois casais. O ve\u00edculo levado no assalto j\u00e1 havia sido recuperado anteriormente pela unidade especializada e devolvido ao propriet\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O avan\u00e7o das apura\u00e7\u00f5es permitiu identificar tr\u00eas envolvidos: uma adolescente, o namorado dela \u2014 maior de idade \u2014 e a mulher presa na opera\u00e7\u00e3o desta segunda-feira. \u201cTanto a adolescente quanto a suspeita presa confessaram participa\u00e7\u00e3o. As dilig\u00eancias continuam para localizar o quarto integrante do grupo\u201d, informou a delegada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A autoridade policial tamb\u00e9m destacou que a\u00e7\u00f5es investigativas sistem\u00e1ticas t\u00eam contribu\u00eddo para a redu\u00e7\u00e3o de crimes dessa natureza na capital. Em 2022, a m\u00e9dia era de cerca de 30 ocorr\u00eancias mensais; atualmente, h\u00e1 per\u00edodos prolongados sem registros. O \u00faltimo caso semelhante foi registrado em agosto e j\u00e1 teve a autoria esclarecida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mulher presa ser\u00e1 submetida \u00e0 audi\u00eancia de cust\u00f3dia e permanecer\u00e1 \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a. As investiga\u00e7\u00f5es prosseguem para a captura do suspeito que ainda n\u00e3o foi localizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil, por meio da Divis\u00e3o de Roubos e Furtos de Ve\u00edculos (DRFV), prendeu na manh\u00e3 da segunda-feira, 24, uma mulher de 20 anos suspeita de integrar o grupo respons\u00e1vel pelo roubo de um ve\u00edculo e de um aparelho celular de um motorista de aplicativo no bairro Coqueiral, em Aracaju. O crime ocorreu em [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/11\/IMG_6608.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6703"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6703\/revisions"}],"predecessor-version":[{"id":6705,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6703\/revisions\/6705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6704"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}