{"id":6722,"date":"2025-11-27T11:11:29","date_gmt":"2025-11-27T14:11:29","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6722"},"modified":"2025-12-15T18:42:26","modified_gmt":"2025-12-15T21:42:26","slug":"confira-a-previsao-do-tempo-em-aracaju-para-esta-quinta-feira-26","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/11\/27\/confira-a-previsao-do-tempo-em-aracaju-para-esta-quinta-feira-26\/","title":{"rendered":"Confira a previs\u00e3o do tempo em Aracaju para esta quinta-feira (26)"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Aracaju ter\u00e1 mais um dia de muita nebulosidade nesta quinta-feira (27), com possibilidade de chuva isolada nas primeiras horas da manh\u00e3. Segundo a previs\u00e3o, as temperaturas variam entre m\u00ednima de 24\u00b0C, com tend\u00eancia de leve eleva\u00e7\u00e3o, e m\u00e1xima de 31\u00b0C, que se mant\u00e9m est\u00e1vel. A umidade relativa do ar oscila de 50% a 90%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No per\u00edodo da manh\u00e3, o c\u00e9u permanece com muitas nuvens e h\u00e1 chance de precipita\u00e7\u00f5es r\u00e1pidas, enquanto os ventos sopram de leste para oeste em intensidade moderada. Durante a tarde, a nebulosidade continua presente, por\u00e9m sem expectativa de chuva, e os ventos ficam mais fracos na mesma dire\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 noite, o cen\u00e1rio segue nublado, com ventos fracos soprando de leste para nordeste. A combina\u00e7\u00e3o de c\u00e9u fechado e ventos de baixa intensidade mant\u00e9m a sensa\u00e7\u00e3o de abafamento na capital sergipana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: F5news<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Aracaju ter\u00e1 mais um dia de muita nebulosidade nesta quinta-feira (27), com possibilidade de chuva isolada nas primeiras horas da manh\u00e3. Segundo a previs\u00e3o, as temperaturas variam entre m\u00ednima de 24\u00b0C, com tend\u00eancia de leve eleva\u00e7\u00e3o, e m\u00e1xima de 31\u00b0C, que se mant\u00e9m est\u00e1vel. A umidade relativa do ar oscila de 50% a 90%. No [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/11\/IMG_6650.webp","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6722"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6722\/revisions"}],"predecessor-version":[{"id":6724,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6722\/revisions\/6724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6723"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}