{"id":6773,"date":"2025-12-05T10:07:27","date_gmt":"2025-12-05T13:07:27","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6773"},"modified":"2026-01-08T08:54:59","modified_gmt":"2026-01-08T11:54:59","slug":"mulher-e-indiciada-por-fraudes-patrimoniais-de-r-14-milhao-em-sergipe","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/12\/05\/mulher-e-indiciada-por-fraudes-patrimoniais-de-r-14-milhao-em-sergipe\/","title":{"rendered":"Mulher \u00e9 indiciada por fraudes patrimoniais de R$ 1,4 milh\u00e3o em Sergipe"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Civil de Sergipe, por meio da Delegacia de Defrauda\u00e7\u00f5es e Combate \u00e0 Pirataria (DDCP), unidade vinculada ao Departamento de Crimes Contra o Patrim\u00f4nio (Depatri), divulgou nesta quinta-feira, 4, que concluiu o inqu\u00e9rito policial que apurou um complexo esquema de fraudes patrimoniais feito por uma mulher. Segundo as investiga\u00e7\u00f5es, ela se aproveitava da rela\u00e7\u00e3o de proximidade com ex-c\u00f4njuges e funcion\u00e1rios de suas pr\u00f3prias empresas para obter vantagens il\u00edcitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a pol\u00edcia, a indiciada inseria as v\u00edtimas como propriet\u00e1rias de suas empresas sem qualquer autoriza\u00e7\u00e3o, com o objetivo de obter benef\u00edcios futuros em nome delas. Em diversas situa\u00e7\u00f5es, iniciadas em 2019, ela teria falsificado assinaturas e, em outras, constrangido as v\u00edtimas a assinarem documentos sem conhecimento pr\u00e9vio do conte\u00fado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como consequ\u00eancia, v\u00e1rios envolvidos passaram a responder a processos de execu\u00e7\u00e3o, enfrentando penhoras de bens e outros constrangimentos judiciais, mesmo sem terem participado de qualquer transa\u00e7\u00e3o comercial. Embora possu\u00edsse patrim\u00f4nio expressivo, a investigada deixou de quitar d\u00edvidas contra\u00eddas com institui\u00e7\u00f5es financeiras e \u00f3rg\u00e3os p\u00fablicos, transferindo os preju\u00edzos a terceiros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O inqu\u00e9rito re\u00fane depoimentos das v\u00edtimas, laudo pericial que confirma as falsifica\u00e7\u00f5es e vasta documenta\u00e7\u00e3o que comprova as d\u00edvidas geradas. Durante as apura\u00e7\u00f5es, surgiram ainda ind\u00edcios de que a investigada planejava assumir novos neg\u00f3cios em outro pa\u00eds e que tentou influenciar uma das testemunhas a n\u00e3o comparecer \u00e0 delegacia \u2014 fatores que refor\u00e7aram o risco de continuidade das pr\u00e1ticas il\u00edcitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante da gravidade dos fatos e da possibilidade de dissipa\u00e7\u00e3o de patrim\u00f4nio, as v\u00edtimas apresentaram representa\u00e7\u00e3o criminal e a Pol\u00edcia Civil pediu o sequestro e a indisponibilidade de bens da investigada. A Justi\u00e7a acatou o pedido, determinando o bloqueio de ativos financeiros e a constri\u00e7\u00e3o patrimonial at\u00e9 o montante de R$ 1,4 milh\u00e3o, valor que corresponde ao preju\u00edzo causado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Civil de Sergipe refor\u00e7a seu compromisso com a prote\u00e7\u00e3o do patrim\u00f4nio dos cidad\u00e3os e com a responsabiliza\u00e7\u00e3o de autores de crimes de fraude e estelionato, especialmente em casos que envolvem abuso de confian\u00e7a e manipula\u00e7\u00e3o de v\u00ednculos pessoais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil de Sergipe, por meio da Delegacia de Defrauda\u00e7\u00f5es e Combate \u00e0 Pirataria (DDCP), unidade vinculada ao Departamento de Crimes Contra o Patrim\u00f4nio (Depatri), divulgou nesta quinta-feira, 4, que concluiu o inqu\u00e9rito policial que apurou um complexo esquema de fraudes patrimoniais feito por uma mulher. Segundo as investiga\u00e7\u00f5es, ela se aproveitava da rela\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6774,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/IMG_6833.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6773"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6773\/revisions"}],"predecessor-version":[{"id":6775,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6773\/revisions\/6775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6774"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}