{"id":6779,"date":"2025-12-08T12:22:31","date_gmt":"2025-12-08T15:22:31","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6779"},"modified":"2026-01-08T08:58:28","modified_gmt":"2026-01-08T11:58:28","slug":"pmse-cumpre-mandados-de-prisao-em-nossa-senhora-do-socorro","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/12\/08\/pmse-cumpre-mandados-de-prisao-em-nossa-senhora-do-socorro\/","title":{"rendered":"PMSE cumpre mandados de pris\u00e3o em Nossa Senhora do Socorro"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Militares do Batalh\u00e3o de Pol\u00edcia de Radiopatrulha (BPRp) cumpriram um mandado de pris\u00e3o na tarde deste domingo, 7, no bairro Guajar\u00e1, em Nossa Senhora do Socorro, regi\u00e3o metropolitana de Aracaju.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o ocorreu durante patrulhamento no Loteamento Santa In\u00eas, quando a equipe visualizou um homem fazendo uso de entorpecente. Ao notar a aproxima\u00e7\u00e3o da viatura policial, ele tentou fugir, mas foi alcan\u00e7ado e abordado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a abordagem, o suspeito forneceu nome falso. Ap\u00f3s consulta junto ao N\u00facleo de Intelig\u00eancia, foi constatada a exist\u00eancia de dois mandados de pris\u00e3o em aberto contra ele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante dos fatos, o homem foi encaminhado \u00e0 Delegacia para a ado\u00e7\u00e3o das medidas legais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Militares do Batalh\u00e3o de Pol\u00edcia de Radiopatrulha (BPRp) cumpriram um mandado de pris\u00e3o na tarde deste domingo, 7, no bairro Guajar\u00e1, em Nossa Senhora do Socorro, regi\u00e3o metropolitana de Aracaju. A a\u00e7\u00e3o ocorreu durante patrulhamento no Loteamento Santa In\u00eas, quando a equipe visualizou um homem fazendo uso de entorpecente. Ao notar a aproxima\u00e7\u00e3o da viatura [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/IMG_6875.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6779"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6779\/revisions"}],"predecessor-version":[{"id":6781,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6779\/revisions\/6781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6780"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}