{"id":6848,"date":"2025-11-21T18:20:38","date_gmt":"2025-11-21T21:20:38","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6848"},"modified":"2025-12-15T18:28:14","modified_gmt":"2025-12-15T21:28:14","slug":"adolescente-de-17-anos-morre-apos-ser-baleado-em-sao-cristovao","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/11\/21\/adolescente-de-17-anos-morre-apos-ser-baleado-em-sao-cristovao\/","title":{"rendered":"Adolescente de 17 anos morre ap\u00f3s ser baleado em S\u00e3o Crist\u00f3v\u00e3o"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um adolescente de 17 anos morreu ap\u00f3s ser baleado no Bairro Baixa Divin\u00e9ia, em S\u00e3o Crist\u00f3v\u00e3o, no in\u00edcio da manh\u00e3 desta sexta-feira (21). A informa\u00e7\u00e3o foi confirmada pela Pol\u00edcia Militar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a PM, uma mulher acionou a pol\u00edcia ap\u00f3s ter ouvido pelo menos cinco disparos de arma de fogo. O suspeito fugiu do local em uma motocicleta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Servi\u00e7o de Atendimento M\u00f3vel (Samu) atendeu a ocorr\u00eancia e atestou o \u00f3bito no local. O Instituto M\u00e9dico Legal (IML) foi acionado para recolher o corpo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quem tiver informa\u00e7\u00f5es que possam contribuir com a investiga\u00e7\u00e3o do crime deve ligar para o Disque-Den\u00fancia pelo n\u00famero 181. A identidade do denunciante ser\u00e1 mantida em sigilo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um adolescente de 17 anos morreu ap\u00f3s ser baleado no Bairro Baixa Divin\u00e9ia, em S\u00e3o Crist\u00f3v\u00e3o, no in\u00edcio da manh\u00e3 desta sexta-feira (21). A informa\u00e7\u00e3o foi confirmada pela Pol\u00edcia Militar.&nbsp; De acordo com a PM, uma mulher acionou a pol\u00edcia ap\u00f3s ter ouvido pelo menos cinco disparos de arma de fogo. O suspeito fugiu do [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/IMG_3890.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6848"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6848\/revisions"}],"predecessor-version":[{"id":6850,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6848\/revisions\/6850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6849"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}