{"id":6870,"date":"2025-12-17T10:05:33","date_gmt":"2025-12-17T13:05:33","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6870"},"modified":"2026-01-08T09:07:36","modified_gmt":"2026-01-08T12:07:36","slug":"motociclista-morre-apos-colidir-com-caminhonete-em-caninde","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/12\/17\/motociclista-morre-apos-colidir-com-caminhonete-em-caninde\/","title":{"rendered":"Motociclista morre ap\u00f3s colidir com caminhonete em Canind\u00e9"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um motociclista morreu ap\u00f3s colidir com uma caminhonete na rodovia SE-230, no munic\u00edpio de Canind\u00e9 de S\u00e3o Francisco. O acidente ocorreu na noite desta ter\u00e7a-feira, 16.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria (BPRv), a equipe foi acionada, atrav\u00e9s do Centro Integrado de Opera\u00e7\u00f5es em Seguran\u00e7a P\u00fablica (CIOSP), para atender uma ocorr\u00eancia nas proximidades do Assentamento Pioneira, em Canind\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chegando ao local, os policiais verificaram que outra guarni\u00e7\u00e3o j\u00e1 se encontrava na regi\u00e3o. Segundo os relatos colhidos pela equipe, a caminhonete estava parada \u00e0 margem da pista, no sentido Po\u00e7o Redondo\/Canind\u00e9, ap\u00f3s o semi-eixo do ve\u00edculo quebrar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O condutor da caminhonete e testemunhas relataram que a via estava sinalizada de forma improvisada, usando galhos de \u00e1rvores. No entanto, o condutor da motocicleta n\u00e3o conseguiu desviar a tempo, colidindo na traseira da caminhonete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A equipe do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) foi acionada e constatou que o motociclista n\u00e3o resistiu aos ferimentos, evoluindo a \u00f3bito ainda no local do acidente. O Instituto M\u00e9dico Legal (IML) e o Instituto de Criminal\u00edstica foram chamados para a realiza\u00e7\u00e3o dos procedimentos cab\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um motociclista morreu ap\u00f3s colidir com uma caminhonete na rodovia SE-230, no munic\u00edpio de Canind\u00e9 de S\u00e3o Francisco. O acidente ocorreu na noite desta ter\u00e7a-feira, 16. De acordo com o Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria (BPRv), a equipe foi acionada, atrav\u00e9s do Centro Integrado de Opera\u00e7\u00f5es em Seguran\u00e7a P\u00fablica (CIOSP), para atender uma ocorr\u00eancia nas proximidades [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":6871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/IMG_7079.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6870"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6870\/revisions"}],"predecessor-version":[{"id":6872,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6870\/revisions\/6872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6871"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}