{"id":6920,"date":"2025-12-30T09:01:36","date_gmt":"2025-12-30T12:01:36","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6920"},"modified":"2026-01-08T09:29:26","modified_gmt":"2026-01-08T12:29:26","slug":"tumulto-na-presidio-de-areia-branca-apos-detento-se-recusar-a-transferencia","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/12\/30\/tumulto-na-presidio-de-areia-branca-apos-detento-se-recusar-a-transferencia\/","title":{"rendered":"Tumulto na pres\u00eddio de Areia Branca ap\u00f3s detento se recusar a transfer\u00eancia"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Nesta segunda-feira (29), um tumulto foi registrado na Cadeia P\u00fablica de Areia Branca, em Sergipe, ap\u00f3s um detento se recusar a ser transferido para o Complexo Penitenci\u00e1rio Ant\u00f4nio Jacinto Filho (Compajaf), em Aracaju. A situa\u00e7\u00e3o gerou um breve confronto entre os internos, mas foi rapidamente controlada pelas autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Secretaria de Estado da Justi\u00e7a (Sejuc) informou que a confus\u00e3o teve in\u00edcio quando o custodiado se op\u00f4s \u00e0 transfer\u00eancia, o que gerou um momento de tens\u00e3o na unidade prisional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A situa\u00e7\u00e3o foi contornada ap\u00f3s di\u00e1logo com os internos e a ado\u00e7\u00e3o dos procedimentos administrativos necess\u00e1rios. O detento foi ent\u00e3o transferido para o Compajaf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A visita programada para a unidade ocorreu normalmente e foi at\u00e9 estendida para compensar o tempo que foi comprometido devido ao tumulto. A Sejuc reafirmou que as transfer\u00eancias de internos s\u00e3o procedimentos rotineiros, realizados para garantir a ordem, a seguran\u00e7a e o bom funcionamento do sistema prisional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: F5news<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira (29), um tumulto foi registrado na Cadeia P\u00fablica de Areia Branca, em Sergipe, ap\u00f3s um detento se recusar a ser transferido para o Complexo Penitenci\u00e1rio Ant\u00f4nio Jacinto Filho (Compajaf), em Aracaju. A situa\u00e7\u00e3o gerou um breve confronto entre os internos, mas foi rapidamente controlada pelas autoridades. A Secretaria de Estado da Justi\u00e7a (Sejuc) [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":6921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/IMG_7263.webp","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6920"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6920\/revisions"}],"predecessor-version":[{"id":6922,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6920\/revisions\/6922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6921"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}