{"id":6932,"date":"2025-12-16T00:00:00","date_gmt":"2025-12-16T03:00:00","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6932"},"modified":"2026-01-08T09:08:13","modified_gmt":"2026-01-08T12:08:13","slug":"governo-do-estado-amplia-acesso-a-cirurgias-eletivas-e-beneficia-mais-de-45-mil-sergipanos","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/12\/16\/governo-do-estado-amplia-acesso-a-cirurgias-eletivas-e-beneficia-mais-de-45-mil-sergipanos\/","title":{"rendered":"Governo do Estado amplia acesso a cirurgias eletivas e beneficia mais de 45 mil sergipanos"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\"><em>Programas Opera e Enxerga Sergipe t\u00eam transformado o dia a dia de pessoas, resgatando a qualidade de vida<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sergipe vive um novo momento no acesso \u00e0s cirurgias eletivas e aos procedimentos especializados pelo Sistema \u00danico de Sa\u00fade (SUS). Por meio dos programas Opera Sergipe e Enxerga Sergipe, o Governo do Estado j\u00e1 beneficiou mais de 45 mil sergipanos, com redu\u00e7\u00e3o de filas, amplia\u00e7\u00e3o do atendimento e, sobretudo, transforma\u00e7\u00e3o real na vida de quem esperava h\u00e1 anos por um procedimento. Somente o Opera Sergipe j\u00e1 ultrapassou a marca de 33 mil cirurgias realizadas, consolidando-se como uma das maiores iniciativas do tipo na hist\u00f3ria do estado.<br>Os n\u00fameros ganham sentido quando se traduzem em hist\u00f3rias como a de Roseanne Correia, 40 anos, que encontrou no Opera Sergipe a chance de recome\u00e7ar. Ap\u00f3s tentar diversas alternativas para emagrecer, sem sucesso, ela realizou a cirurgia bari\u00e1trica pelo programa e viu sua vida mudar completamente. \u201cJ\u00e1 perdi mais de 30 quilos. A bari\u00e1trica representa vida para mim. Recuperei minha alegria, meu bem-estar e at\u00e9 coisas simples, como brincar no ch\u00e3o com meus filhos. Hoje me olho no espelho com carinho, me sinto bonita, minha autoestima melhorou muito e isso refletiu at\u00e9 no meu casamento\u201d, conta.<br>Em apenas nove meses da segunda fase do Opera Sergipe, o Estado j\u00e1 realizou mais do que o dobro de cirurgias bari\u00e1tricas feitas pelo servi\u00e7o p\u00fablico nos \u00faltimos 18 anos. Ao todo, j\u00e1 s\u00e3o 451 procedimentos, resultado de uma pol\u00edtica p\u00fablica que prioriza o cuidado humanizado, a amplia\u00e7\u00e3o da rede credenciada e a agilidade no atendimento, garantindo que mais pessoas tenham acesso ao procedimento que aguardavam.<br>Outra hist\u00f3ria marcada pela transforma\u00e7\u00e3o \u00e9 a do agente administrativo Wanderson G\u00f3is, 29 anos, de Itabaiana. Para ele, a cirurgia bari\u00e1trica significou mais do que sa\u00fade: foi uma decis\u00e3o pensada no futuro da fam\u00edlia. \u201cA bari\u00e1trica me deu a chance de ter uma vida melhor e recuperar a autoestima. Estou construindo minha fam\u00edlia e quero ter sa\u00fade para acompanhar o crescimento dos meus filhos, brincar, correr e estar presente de verdade na vida deles\u201d, relata.<br>Mais cuidado para as mulheres<br>Na segunda fase do programa, um avan\u00e7o importante foi a cria\u00e7\u00e3o do Opera Mulher, iniciativa voltada exclusivamente para a sa\u00fade feminina. A a\u00e7\u00e3o ampliou o acesso a cirurgias como endometriose, redu\u00e7\u00e3o e reconstru\u00e7\u00e3o mam\u00e1ria, al\u00e9m de procedimentos j\u00e1 ofertados anteriormente, como laqueadura e histerectomia, atendendo demandas que impactam diretamente a qualidade de vida das mulheres sergipanas.<br>Al\u00e9m das cirurgias eletivas, o Enxerga Sergipe tem devolvido a vis\u00e3o e a autonomia a milhares de pessoas. Mais de 11 mil sergipanos j\u00e1 foram beneficiados com procedimentos oftalmol\u00f3gicos, como a cirurgia de catarata. \u00c9 o caso do aposentado Paulo Roberto, 69 anos, de Cedro de S\u00e3o Jo\u00e3o, que voltou a enxergar com nitidez ap\u00f3s o procedimento. \u201cN\u00e3o enxergar bem \u00e9 desesperador. Quando soube que poderia fazer a cirurgia rapidamente, fiquei muito feliz. Agora vou conseguir retomar h\u00e1bitos simples, como ler livros, algo que eu sentia muita falta\u201d, afirma.<br>Como participar<br>Para ter acesso ao Opera Sergipe, o primeiro passo \u00e9 procurar a Unidade B\u00e1sica de Sa\u00fade (UBS) do munic\u00edpio. A partir da avalia\u00e7\u00e3o m\u00e9dica, o paciente \u00e9 encaminhado para a regula\u00e7\u00e3o estadual, que organiza o acesso aos procedimentos conforme os crit\u00e9rios cl\u00ednicos e a disponibilidade na rede credenciada. O programa contempla diversas cirurgias eletivas, garantindo atendimento gratuito pelo SUS em diferentes regi\u00f5es do estado.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"720\" data-id=\"6934\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/614381d6-6633-4748-b3fd-0ef528bc8d4c-1024x720.jpeg\" alt=\"\" class=\"wp-image-6934\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/614381d6-6633-4748-b3fd-0ef528bc8d4c-1024x720.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/614381d6-6633-4748-b3fd-0ef528bc8d4c-300x211.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/614381d6-6633-4748-b3fd-0ef528bc8d4c-768x540.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/614381d6-6633-4748-b3fd-0ef528bc8d4c.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"720\" data-id=\"6935\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/b37d1a04-99a1-434a-9b06-a4ebcd2c230b-1024x720.jpeg\" alt=\"\" class=\"wp-image-6935\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/b37d1a04-99a1-434a-9b06-a4ebcd2c230b-1024x720.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/b37d1a04-99a1-434a-9b06-a4ebcd2c230b-300x211.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/b37d1a04-99a1-434a-9b06-a4ebcd2c230b-768x540.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/b37d1a04-99a1-434a-9b06-a4ebcd2c230b.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"6936\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/7e825bbb-1110-4e3f-878d-9ed3ef77398c.jpeg\" alt=\"\" class=\"wp-image-6936\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/7e825bbb-1110-4e3f-878d-9ed3ef77398c.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/7e825bbb-1110-4e3f-878d-9ed3ef77398c-300x200.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/7e825bbb-1110-4e3f-878d-9ed3ef77398c-768x512.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/7e825bbb-1110-4e3f-878d-9ed3ef77398c-360x240.jpeg 360w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"568\" data-id=\"6937\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/a199721c-2fe0-48db-8609-cf58f222f17e-1024x568.jpeg\" alt=\"\" class=\"wp-image-6937\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/a199721c-2fe0-48db-8609-cf58f222f17e-1024x568.jpeg 1024w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/a199721c-2fe0-48db-8609-cf58f222f17e-300x166.jpeg 300w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/a199721c-2fe0-48db-8609-cf58f222f17e-768x426.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/a199721c-2fe0-48db-8609-cf58f222f17e.jpeg 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Programas Opera e Enxerga Sergipe t\u00eam transformado o dia a dia de pessoas, resgatando a qualidade de vida Sergipe vive um novo momento no acesso \u00e0s cirurgias eletivas e aos procedimentos especializados pelo Sistema \u00danico de Sa\u00fade (SUS). Por meio dos programas Opera Sergipe e Enxerga Sergipe, o Governo do Estado j\u00e1 beneficiou mais de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/12\/870c6120-5c7f-43f6-988b-97bf6ba2d4a5.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6932"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6932\/revisions"}],"predecessor-version":[{"id":6938,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6932\/revisions\/6938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6933"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}