{"id":6985,"date":"2026-01-12T13:45:51","date_gmt":"2026-01-12T16:45:51","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=6985"},"modified":"2026-01-12T13:45:53","modified_gmt":"2026-01-12T16:45:53","slug":"incendio-atinge-duas-embarcacoes-no-rio-sergipe-em-aracaju","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2026\/01\/12\/incendio-atinge-duas-embarcacoes-no-rio-sergipe-em-aracaju\/","title":{"rendered":"INC\u00caNDIO ATINGE DUAS EMBARCA\u00c7\u00d5ES NO RIO SERGIPE, EM ARACAJU"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Duas embarca\u00e7\u00f5es pegaram fogo na noite do \u00faltimo s\u00e1bado (10) no rio Sergipe, na regi\u00e3o do bairro Coroa do Meio, em Aracaju. O inc\u00eandio mobilizou equipes do Corpo de Bombeiros Militar de Sergipe e foi controlado sem registro de feridos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com os Bombeiros, o chamado foi registrado por volta das 20h40. Ao chegar ao local, as equipes constataram que dois barcos estavam em chamas: um deles atracado em uma marina e o outro na margem oposta do rio. A informa\u00e7\u00e3o repassada pela administra\u00e7\u00e3o da marina \u00e9 de que as embarca\u00e7\u00f5es estavam lado a lado quando o fogo come\u00e7ou e que, durante o inc\u00eandio, uma delas acabou se soltando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O combate \u00e0s chamas foi realizado por guarni\u00e7\u00f5es dos quart\u00e9is Central e da Orla da Atalaia. Para controlar o fogo, foram utilizados cerca de 7 mil litros de \u00e1gua e L\u00edquido Gerador de Espuma. O barco que se desprendeu foi combatido a partir da margem, com o apoio do canh\u00e3o de uma viatura de combate a inc\u00eandio, devido \u00e0 presen\u00e7a de \u00e1rea de manguezal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a ocorr\u00eancia, os respons\u00e1veis pelas embarca\u00e7\u00f5es e pela marina foram orientados a solicitar per\u00edcia para apurar as causas do inc\u00eandio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: A8se<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Duas embarca\u00e7\u00f5es pegaram fogo na noite do \u00faltimo s\u00e1bado (10) no rio Sergipe, na regi\u00e3o do bairro Coroa do Meio, em Aracaju. O inc\u00eandio mobilizou equipes do Corpo de Bombeiros Militar de Sergipe e foi controlado sem registro de feridos. De acordo com os Bombeiros, o chamado foi registrado por volta das 20h40. Ao chegar [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2026\/01\/IMG_7512.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6985"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6985\/revisions"}],"predecessor-version":[{"id":6987,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6985\/revisions\/6987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/6986"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}