{"id":7020,"date":"2026-01-19T12:22:19","date_gmt":"2026-01-19T15:22:19","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=7020"},"modified":"2026-01-19T12:22:21","modified_gmt":"2026-01-19T15:22:21","slug":"homens-armados-assaltam-minimercado-em-aracaju-e-causam-prejuizo-de-quase-r-60-mil","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2026\/01\/19\/homens-armados-assaltam-minimercado-em-aracaju-e-causam-prejuizo-de-quase-r-60-mil\/","title":{"rendered":"homens armados assaltam minimercado em Aracaju e causam preju\u00edzo de quase R$ 60 mil"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Uma c\u00e2mera de seguran\u00e7a flagrou um assalto a um minimercado no Conjunto Santa Tereza, Bairro Aeroporto, Zona Sul de&nbsp;<a class=\"\" href=\"https:\/\/g1.globo.com\/se\/sergipe\/cidade\/aracaju\/\">Aracaju<\/a>, nesse s\u00e1bado (17). Nas imagens, \u00e9 poss\u00edvel ver o momento em que dois homens armados chegam, descem de uma moto e assaltam o estabelecimento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O propriet\u00e1rio do minimercado, Hugo Souza, contou que a dupla agiu muito r\u00e1pido e que, quando percebeu, um deles j\u00e1 estava em sua frente anunciando o assalto.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEles levaram toda a gaveta do caixa, onde tinha cerca de R$ 5 mil. Tamb\u00e9m levaram minha corrente, minha pulseira e meu anel, todos de ouro. Um preju\u00edzo de aproximadamente R$ 60 mil\u201d, disse.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Hugo registrou um boletim de ocorr\u00eancia e conta com a ajuda da pol\u00edcia e da popula\u00e7\u00e3o para localizar os suspeitos. Informa\u00e7\u00f5es podem ser passadas pelo Disque-Den\u00fancia 181, n\u00e3o \u00e9 preciso se identificar.\u00a0<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Uma c\u00e2mera de seguran\u00e7a flagrou um assalto a um minimercado no Conjunto Santa Tereza, Bairro Aeroporto, Zona Sul de&nbsp;Aracaju, nesse s\u00e1bado (17). Nas imagens, \u00e9 poss\u00edvel ver o momento em que dois homens armados chegam, descem de uma moto e assaltam o estabelecimento.&nbsp; O propriet\u00e1rio do minimercado, Hugo Souza, contou que a dupla agiu muito [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7021,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2026\/01\/IMG_7640.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7020"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7020\/revisions"}],"predecessor-version":[{"id":7022,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7020\/revisions\/7022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/7021"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}