{"id":7123,"date":"2026-02-11T13:36:36","date_gmt":"2026-02-11T16:36:36","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=7123"},"modified":"2026-02-13T10:13:31","modified_gmt":"2026-02-13T13:13:31","slug":"homem-e-autuado-por-criacao-irregular-de-camaroes-em-estancia","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2026\/02\/11\/homem-e-autuado-por-criacao-irregular-de-camaroes-em-estancia\/","title":{"rendered":"Homem \u00e9 autuado por cria\u00e7\u00e3o irregular de camar\u00f5es em Est\u00e2ncia"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um homem foi autuado por crime ambiental ap\u00f3s desenvolver a atividade de carcinicultura irregular, considerada uma atividade potencialmente poluidora. O caso ocorreu na manh\u00e3 desta ter\u00e7a-feira, 10, no povoado Porto do Mato, em Est\u00e2ncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Pol\u00edcia Militar (PMSE), um pescador foi flagrado pelas equipes, criando os camar\u00f5es em \u00e1rea de interesse da Uni\u00e3o, sem a devida licen\u00e7a ou autoriza\u00e7\u00e3o do \u00f3rg\u00e3o ambiental competente, e sem a autoriza\u00e7\u00e3o da Secretaria do Patrim\u00f4nio da Uni\u00e3o (SPU).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No momento da abordagem, o suspeito n\u00e3o apresentou uma licen\u00e7a ambiental v\u00e1lida e declarou espontaneamente que tenta regularizar a licen\u00e7a desde o ano de 2019, permanecendo, contudo, em funcionamento irregular.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os fiscais da SPU procederam \u00e0 notifica\u00e7\u00e3o administrativa do autor do fato, adotando as provid\u00eancias cab\u00edveis e o homem foi devidamente cientificado e compromissado a comparecer em Ju\u00edzo quando intimado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o foi realizada pela Pol\u00edcia Militar de Sergipe, por meio da Companhia Independente de Pol\u00edcia Ambiental (CIPAm), em fiscaliza\u00e7\u00e3o conjunta com a SPU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um homem foi autuado por crime ambiental ap\u00f3s desenvolver a atividade de carcinicultura irregular, considerada uma atividade potencialmente poluidora. O caso ocorreu na manh\u00e3 desta ter\u00e7a-feira, 10, no povoado Porto do Mato, em Est\u00e2ncia. Segundo a Pol\u00edcia Militar (PMSE), um pescador foi flagrado pelas equipes, criando os camar\u00f5es em \u00e1rea de interesse da Uni\u00e3o, sem [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2026\/02\/IMG_8086.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7123"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7123\/revisions"}],"predecessor-version":[{"id":7125,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7123\/revisions\/7125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/7124"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}