{"id":7197,"date":"2026-02-23T10:59:47","date_gmt":"2026-02-23T13:59:47","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=7197"},"modified":"2026-03-12T02:27:18","modified_gmt":"2026-03-12T05:27:18","slug":"ficco-se-prende-homem-de-60-anos-foragido-por-estupro-de-vulneravel","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2026\/02\/23\/ficco-se-prende-homem-de-60-anos-foragido-por-estupro-de-vulneravel\/","title":{"rendered":"FICCO\/SE prende homem de 60 anos foragido por estupro de vulner\u00e1vel"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">No \u00faltimo domingo, 22, a For\u00e7a Integrada de Combate ao Crime Organizado em Sergipe (FICCO\/SE), com o apoio do 6\u00ba Batalh\u00e3o da Pol\u00edcia Militar (6\u00ba BPM) e o compartilhamento de informa\u00e7\u00f5es de intelig\u00eancia com a FICCO\/BA, localizou e prendeu um homem de 60 anos no munic\u00edpio de Est\u00e2ncia\/SE. O investigado era foragido da Justi\u00e7a do Estado de S\u00e3o Paulo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pris\u00e3o ocorreu na Rodovia BR-101, nas proximidades da cidade de Est\u00e2ncia, no momento em que o procurado viajava em um \u00f4nibus interestadual oriundo do estado da Bahia. O homem possu\u00eda um mandado de pris\u00e3o preventiva em aberto pelo crime de estupro de vulner\u00e1vel, expedido em 2023 pelo Ju\u00edzo da 2\u00aa Vara Criminal da Comarca de Atibaia\/SP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o art. 217-A do C\u00f3digo Penal Brasileiro, a pena para o crime de estupro de vulner\u00e1vel pode chegar a 30 anos de reclus\u00e3o, dependendo de circunst\u00e2ncias agravantes. Ap\u00f3s o cumprimento do mandado, o preso foi encaminhado ao sistema penitenci\u00e1rio estadual, onde permanecer\u00e1 \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a paulista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apenas nos primeiros 60&nbsp;dias de 2026, as a\u00e7\u00f5es da FICCO\/SE j\u00e1 resultaram na pris\u00e3o de 12 pessoas no estado \u2014 incluindo foragidos capturados e envolvidos em crimes de tr\u00e1fico de drogas e lavagem de capitais \u2014, al\u00e9m da apreens\u00e3o de mais de uma tonelada de entorpecentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A FICCO\/SE \u00e9 composta por integrantes da Pol\u00edcia Federal, Pol\u00edcia Civil, Pol\u00edcia Militar, Pol\u00edcia Penal e Secretaria Nacional de Pol\u00edticas Penais (Senappen), e tem como objetivo a integra\u00e7\u00e3o das for\u00e7as de seguran\u00e7a em a\u00e7\u00f5es de combate ao crime organizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9ditos: Lagartense.com.br <\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo domingo, 22, a For\u00e7a Integrada de Combate ao Crime Organizado em Sergipe (FICCO\/SE), com o apoio do 6\u00ba Batalh\u00e3o da Pol\u00edcia Militar (6\u00ba BPM) e o compartilhamento de informa\u00e7\u00f5es de intelig\u00eancia com a FICCO\/BA, localizou e prendeu um homem de 60 anos no munic\u00edpio de Est\u00e2ncia\/SE. O investigado era foragido da Justi\u00e7a do [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7198,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2026\/02\/IMG_8433.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7197"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7197\/revisions"}],"predecessor-version":[{"id":7199,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7197\/revisions\/7199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/7198"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}