{"id":7207,"date":"2026-02-25T11:38:21","date_gmt":"2026-02-25T14:38:21","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=7207"},"modified":"2026-03-12T02:26:41","modified_gmt":"2026-03-12T05:26:41","slug":"gestao-de-fabio-ja-injetou-mais-de-r-1-milhao-desde-2023-em-seguranca-escolar","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2026\/02\/25\/gestao-de-fabio-ja-injetou-mais-de-r-1-milhao-desde-2023-em-seguranca-escolar\/","title":{"rendered":"Gest\u00e3o de F\u00e1bio j\u00e1 injetou mais de R$ 1 milh\u00e3o desde 2023 em seguran\u00e7a escolar"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A gest\u00e3o do governador F\u00e1bio Mitidieri j\u00e1 destinou mais de R$ 1 milh\u00e3o, entre 2023 e 2025, para fortalecer a seguran\u00e7a nas escolas da rede estadual de Sergipe. Os recursos foram aplicados na contrata\u00e7\u00e3o e capacita\u00e7\u00e3o de pessoal, aquisi\u00e7\u00e3o de viaturas e amplia\u00e7\u00e3o do sistema de videomonitoramento, consolidando uma pol\u00edtica voltada \u00e0 prote\u00e7\u00e3o do patrim\u00f4nio p\u00fablico e da comunidade escolar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Criada em 2019, a Divis\u00e3o de Seguran\u00e7a Escolar, vinculada \u00e0 Secretaria de Estado da Educa\u00e7\u00e3o (Seed), apresentou resultados expressivos ao longo dos anos. Segundo dados oficiais, houve redu\u00e7\u00e3o superior a 92% nos casos de furtos e danos ao patrim\u00f4nio das unidades. Antes da implanta\u00e7\u00e3o do sistema, eram registrados de dois a tr\u00eas arrombamentos por semana, o que gerava preju\u00edzos estimados entre R$ 100 mil e R$ 200 mil ao Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a amplia\u00e7\u00e3o das a\u00e7\u00f5es, o trabalho deixou de focar apenas na prote\u00e7\u00e3o f\u00edsica das escolas e passou a abranger tamb\u00e9m a seguran\u00e7a de alunos, professores e servidores. As equipes atuam em regime de plant\u00e3o 24 horas, apoiadas por videomonitoramento e pelo bot\u00e3o de p\u00e2nico instalado nas unidades, o que permite resposta r\u00e1pida a situa\u00e7\u00f5es de risco, presen\u00e7a de pessoas estranhas ou conflitos no ambiente escolar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente, todas as 318 escolas da rede estadual contam com sistema de monitoramento, garantindo cobertura total. A gest\u00e3o tamb\u00e9m investe na qualifica\u00e7\u00e3o cont\u00ednua de vigilantes e gestores por meio do programa Escola Mais Segura. Para o governo, a estrat\u00e9gia consolida Sergipe entre os estados com modelo mais avan\u00e7ado de seguran\u00e7a escolar, com tecnologia e protocolos que ampliam a preven\u00e7\u00e3o e a tranquilidade nas unidades de ensino.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A gest\u00e3o do governador F\u00e1bio Mitidieri j\u00e1 destinou mais de R$ 1 milh\u00e3o, entre 2023 e 2025, para fortalecer a seguran\u00e7a nas escolas da rede estadual de Sergipe. Os recursos foram aplicados na contrata\u00e7\u00e3o e capacita\u00e7\u00e3o de pessoal, aquisi\u00e7\u00e3o de viaturas e amplia\u00e7\u00e3o do sistema de videomonitoramento, consolidando uma pol\u00edtica voltada \u00e0 prote\u00e7\u00e3o do patrim\u00f4nio [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2026\/02\/0dbfa857-029f-4ae5-8863-c5120365fedf.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7207"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7207\/revisions"}],"predecessor-version":[{"id":7209,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7207\/revisions\/7209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/7208"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}