{"id":7523,"date":"2026-04-27T11:14:43","date_gmt":"2026-04-27T14:14:43","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=7523"},"modified":"2026-05-01T11:10:47","modified_gmt":"2026-05-01T14:10:47","slug":"idoso-morre-apos-ser-atropelado-na-se-285-entre-araua-e-pedrinhas","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2026\/04\/27\/idoso-morre-apos-ser-atropelado-na-se-285-entre-araua-e-pedrinhas\/","title":{"rendered":"Idoso morre ap\u00f3s ser atropelado na SE-285, entre Arau\u00e1 e Pedrinhas"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um idoso de 64 anos morreu ap\u00f3s ser atropelado na rodovia SE-285, nas proximidades da ponte que liga os munic\u00edpios de Arau\u00e1 e Pedrinhas. A informa\u00e7\u00e3o foi confirmada pelo Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual (BPRv).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a equipe, o motorista seguia pela rodovia quando o pedestre tentou atravessar a pista para recolher objetos. O condutor ainda tentou desviar, mas n\u00e3o conseguiu evitar o atropelamento. A v\u00edtima morreu no local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Equipes do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia estiveram na ocorr\u00eancia e confirmaram o \u00f3bito. A per\u00edcia e o Instituto M\u00e9dico Legal tamb\u00e9m foram acionados para os procedimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o BPRv, o motorista prestou socorro inicialmente e deixou o local por medo, mas depois se apresentou \u00e0 delegacia, onde realizou o teste do baf\u00f4metro. N\u00e3o foram constatadas irregularidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O tr\u00e2nsito ficou sob controle at\u00e9 a conclus\u00e3o dos trabalhos no local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: A8se<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um idoso de 64 anos morreu ap\u00f3s ser atropelado na rodovia SE-285, nas proximidades da ponte que liga os munic\u00edpios de Arau\u00e1 e Pedrinhas. A informa\u00e7\u00e3o foi confirmada pelo Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual (BPRv). Segundo a equipe, o motorista seguia pela rodovia quando o pedestre tentou atravessar a pista para recolher objetos. O condutor [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2026\/04\/IMG_9677.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7523"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7523\/revisions"}],"predecessor-version":[{"id":7525,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7523\/revisions\/7525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/7524"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}